{"id":37967,"date":"2025-10-08T09:35:03","date_gmt":"2025-10-08T06:35:03","guid":{"rendered":"https:\/\/web-dev.iptp.net\/?p=37967"},"modified":"2026-04-16T12:18:54","modified_gmt":"2026-04-16T09:18:54","slug":"a-glimpse-into-vietnams-digital-future","status":"publish","type":"post","link":"https:\/\/web.la.iptp.net\/zh_HK\/a-glimpse-into-vietnams-digital-future\/","title":{"rendered":"\u900f\u8996\u8d8a\u5357\u6578\u5b57\u5316\u7684\u672a\u4f86"},"content":{"rendered":"<p>Vietnam&rsquo;s flagship national forum on digital infrastructure &mdash; <strong>DIGIINFRA 2025<\/strong> &mdash; has officially concluded, leaving behind inspiring ideas, meaningful connections, and a shared vision for a stronger digital future.<\/p><p>From vibrant discussions to impactful showcases, the event once again demonstrated that collaboration and innovation remain at the core of digital transformation.<\/p><p><strong>IPTP Networks and DeCenter<\/strong> are proud to have been part of this remarkable gathering &mdash; where technology, strategy, and vision came together to shape the next chapter of Vietnam&rsquo;s digital landscape.<\/p><p>Our sincere gratitude goes to the <strong>Vietnam Internet Association (VIA)<\/strong> for organizing an exceptional event that continues to drive Vietnam&rsquo;s digital vision forward.<\/p><p>Take a look back at some of the memorable moments of IPTP Networks at DIGIINFRA 2025 below.<\/p><p><strong>Get in Touch:<\/strong><br>\nEmail: <span class=\"sp-user\">sales<\/span><span class=\"sp-domain\">iptp.net<\/span><\/p><div class=\"swiper sw-post position-relative overflow-hidden\" id=\"sw-post\">\r\n  <div class=\"swiper-wrapper\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\r\n\r\n\r\n\t\t    <div id=\"slide_1\" class=\"swiper-slide\">\r\n\t      <a href=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo21.jpg\" data-pswp-width=\"1600\" data-pswp-height=\"900\" target=\"_blank\" data-fancybox=\"gallery\">\r\n\t        <img src=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo21.jpg\" alt=\"Ablum\" class=\"disabled-lazy\">         \r\n\t      <\/a>\r\n\t<\/div>\r\n\t\t    <div id=\"slide_2\" class=\"swiper-slide\">\r\n\t      <a href=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo25.jpg\" data-pswp-width=\"1600\" data-pswp-height=\"900\" target=\"_blank\" data-fancybox=\"gallery\">\r\n\t        <img src=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo25.jpg\" alt=\"Ablum\" class=\"disabled-lazy\">         \r\n\t      <\/a>\r\n\t<\/div>\r\n\t\t    <div id=\"slide_3\" class=\"swiper-slide\">\r\n\t      <a href=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo24.jpg\" data-pswp-width=\"1600\" data-pswp-height=\"900\" target=\"_blank\" data-fancybox=\"gallery\">\r\n\t        <img src=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo24.jpg\" alt=\"Ablum\" class=\"disabled-lazy\">         \r\n\t      <\/a>\r\n\t<\/div>\r\n\t\t    <div id=\"slide_4\" class=\"swiper-slide\">\r\n\t      <a href=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo23.jpg\" data-pswp-width=\"1600\" data-pswp-height=\"900\" target=\"_blank\" data-fancybox=\"gallery\">\r\n\t        <img src=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo23.jpg\" alt=\"Ablum\" class=\"disabled-lazy\">         \r\n\t      <\/a>\r\n\t<\/div>\r\n\t\t    <div id=\"slide_5\" class=\"swiper-slide\">\r\n\t      <a href=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo22sq.jpg\" data-pswp-width=\"1600\" data-pswp-height=\"900\" target=\"_blank\" data-fancybox=\"gallery\">\r\n\t        <img src=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo22sq.jpg\" alt=\"Ablum\" class=\"disabled-lazy\">         \r\n\t      <\/a>\r\n\t<\/div>\r\n\t\t    <div id=\"slide_6\" class=\"swiper-slide\">\r\n\t      <a href=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo17sq.jpg\" data-pswp-width=\"1600\" data-pswp-height=\"900\" target=\"_blank\" data-fancybox=\"gallery\">\r\n\t        <img src=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo17sq.jpg\" alt=\"Ablum\" class=\"disabled-lazy\">         \r\n\t      <\/a>\r\n\t<\/div>\r\n\t\t    <div id=\"slide_7\" class=\"swiper-slide\">\r\n\t      <a href=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo16sq.jpg\" data-pswp-width=\"1600\" data-pswp-height=\"900\" target=\"_blank\" data-fancybox=\"gallery\">\r\n\t        <img src=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo16sq.jpg\" alt=\"Ablum\" class=\"disabled-lazy\">         \r\n\t      <\/a>\r\n\t<\/div>\r\n\t\t    <div id=\"slide_8\" class=\"swiper-slide\">\r\n\t      <a href=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo12.jpg\" data-pswp-width=\"1600\" data-pswp-height=\"900\" target=\"_blank\" data-fancybox=\"gallery\">\r\n\t        <img src=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo12.jpg\" alt=\"Ablum\" class=\"disabled-lazy\">         \r\n\t      <\/a>\r\n\t<\/div>\r\n\t\t    <div id=\"slide_9\" class=\"swiper-slide\">\r\n\t      <a href=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo9.jpg\" data-pswp-width=\"1600\" data-pswp-height=\"900\" target=\"_blank\" data-fancybox=\"gallery\">\r\n\t        <img src=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo9.jpg\" alt=\"Ablum\" class=\"disabled-lazy\">         \r\n\t      <\/a>\r\n\t<\/div>\r\n\t\t    <div id=\"slide_10\" class=\"swiper-slide\">\r\n\t      <a href=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo7.jpg\" data-pswp-width=\"1600\" data-pswp-height=\"900\" target=\"_blank\" data-fancybox=\"gallery\">\r\n\t        <img src=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo7.jpg\" alt=\"Ablum\" class=\"disabled-lazy\">         \r\n\t      <\/a>\r\n\t<\/div>\r\n\t\t    <div id=\"slide_11\" class=\"swiper-slide\">\r\n\t      <a href=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo5.jpg\" data-pswp-width=\"1600\" data-pswp-height=\"900\" target=\"_blank\" data-fancybox=\"gallery\">\r\n\t        <img src=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo5.jpg\" alt=\"Ablum\" class=\"disabled-lazy\">         \r\n\t      <\/a>\r\n\t<\/div>\r\n\t\t    <div id=\"slide_12\" class=\"swiper-slide\">\r\n\t      <a href=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo4.jpg\" data-pswp-width=\"1600\" data-pswp-height=\"900\" target=\"_blank\" data-fancybox=\"gallery\">\r\n\t        <img src=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo4.jpg\" alt=\"Ablum\" class=\"disabled-lazy\">         \r\n\t      <\/a>\r\n\t<\/div>\r\n\t\t    <div id=\"slide_13\" class=\"swiper-slide\">\r\n\t      <a href=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo1.jpg\" data-pswp-width=\"1600\" data-pswp-height=\"900\" target=\"_blank\" data-fancybox=\"gallery\">\r\n\t        <img src=\"https:\/\/web.la.iptp.net\/wp-content\/uploads\/digiinfra2025-photo1.jpg\" alt=\"Ablum\" class=\"disabled-lazy\">         \r\n\t      <\/a>\r\n\t<\/div>\r\n\t\t<\/div>\r\n  \r\n  <div class=\"swiper-button-prev\"><\/div>\r\n  <div class=\"swiper-button-next\"><\/div>\r\n  <div class=\"swiper-pagination\"><\/div>\r\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":17,"featured_media":37981,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/web.la.iptp.net\/zh_HK\/wp-json\/wp\/v2\/posts\/37967"}],"collection":[{"href":"https:\/\/web.la.iptp.net\/zh_HK\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.la.iptp.net\/zh_HK\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/zh_HK\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/zh_HK\/wp-json\/wp\/v2\/comments?post=37967"}],"version-history":[{"count":17,"href":"https:\/\/web.la.iptp.net\/zh_HK\/wp-json\/wp\/v2\/posts\/37967\/revisions"}],"predecessor-version":[{"id":42373,"href":"https:\/\/web.la.iptp.net\/zh_HK\/wp-json\/wp\/v2\/posts\/37967\/revisions\/42373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/zh_HK\/wp-json\/wp\/v2\/media\/37981"}],"wp:attachment":[{"href":"https:\/\/web.la.iptp.net\/zh_HK\/wp-json\/wp\/v2\/media?parent=37967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.la.iptp.net\/zh_HK\/wp-json\/wp\/v2\/categories?post=37967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.la.iptp.net\/zh_HK\/wp-json\/wp\/v2\/tags?post=37967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}