{"id":280,"date":"2016-10-07T17:49:02","date_gmt":"2016-10-07T14:49:02","guid":{"rendered":"https:\/\/web-mng.iptp.com\/?page_id=280"},"modified":"2026-01-15T05:58:59","modified_gmt":"2026-01-15T02:58:59","slug":"ip-calculator","status":"publish","type":"page","link":"https:\/\/web.la.iptp.net\/zh_CN\/iptp-tools\/ip-calculator\/","title":{"rendered":"IP \u8ba1\u7b97\u5668"},"content":{"rendered":"<div class=\"section\">\r\n  <div class=\"inner\">\r\n    <div class=\"subtitle text-center\"><a href=\"https:\/\/web.la.iptp.net\/zh_CN\/products-and-services-ecosystem\/\"><span>&#20135;&#21697;&#21644;&#26381;&#21153;&#29983;&#24577;&#31995;&#32479;<\/span><\/a><\/div>\r\n    <h2 class=\"text-center\">&#20102;&#35299; IPTP Networks &#35299;&#20915;&#26041;&#26696;<\/h2>\r\n    <p class=\"text-center\">\r\n      &#25105;&#20204;&#26159;&#19968;&#23478;&#39046;&#20808;&#30340;&#20114;&#32852;&#32593;&#26381;&#21153;&#20379;&#24212;&#21830;&#12289;&#31995;&#32479;&#38598;&#25104;&#21830;&#12289;<br>&#19968;&#32423;&#21333;&#26426;&#32593;&#32476;&#21644;&#20840;&#29699;&#36719;&#20214;&#24320;&#21457;&#20225;&#19994;&#38598;&#22242;&#65292;&#19994;&#21153;&#36941;&#24067;&#20840;&#29699;&#12290;    \r\n    <\/p>\r\n    <div class=\"row row-cols-lg-4 row-cols-sm-2 row-cols-1 g-4 solutions-list pb-3 pt-3\">\r\n        <div class=\"col\">\r\n          <div class=\"solutions-list__item lift\">\r\n            <div class=\"solutions-list__item--body\">\r\n             <div class=\"--icon\"><img class=\"lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" data-src=\"\/wp-content\/uploads\/connectivity-icon-w.svg\" alt=\"Connectivity\"><\/div>\r\n            <div class=\"solutions-list__item-title\"><a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/connectivity-services\/\" class=\"stretched-link\">&#36830;&#25509;<\/a><\/div>\r\n             <div class=\"solutions-list__item-desc\">\r\n\r\n\r\n\r\n             <!-- <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/direct-internet-access\/\">DIA<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/ip-transit\/\">IP transit<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/ix-transit\/\">IX transit<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/remote-dia\/\">Remote DIA<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/remote-ix\/\">Remote IX<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/remote-ix-transit\/\">Remote IX Transit<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/business-solutions\/managed-services\/dmms\/\">DDoS mitigation (DMMS)<\/a> -->\r\n\r\n                                                  <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/blog\/what-is-mpls-multiprotocol-label-switching\/\">MPLS, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/blog\/what-is-iplc\/\">IPLC, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/blog\/what-is-epl\/\">EPL\/IEPL, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/connectivity-services\/\">&#19987;&#32447;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/connectivity-services\/eompls-pseudowire-service\/\">EoMPLS Pseudowire, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/direct-connection-to-cloud-providers\/\">&#20113;&#36830;&#25509;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/jumbo-internet-exchange\/\">JumboIX, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/low-latency-routes\/\">&#20302;&#24310;&#36831;&#36335;&#30001;<\/a>\r\n                              \r\n\r\n             <\/div>\r\n             \r\n            <\/div>\r\n            <div class=\"solutions-list__item--bottom\">\r\n              <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/\" class=\"underline --gray crcl\">&#20102;&#35299;&#26356;&#22810;<\/a>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n        <div class=\"col\">\r\n          <div class=\"solutions-list__item lift\">\r\n            <div class=\"solutions-list__item--body\">\r\n            \r\n             <div class=\"--icon\"><img class=\"lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" data-src=\"\/wp-content\/uploads\/bestpath2.svg\" alt=\"Internet\"><\/div>\r\n              \r\n              <div class=\"solutions-list__item-title\"><a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/\" class=\"\">&#20114;&#32852;&#32593;<\/a><\/div>\r\n              <div class=\"solutions-list__item-desc\">\r\n\r\n              <!-- <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/direct-connection-to-cloud-providers\/\">Cloud Connect<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/what-is-epl\/\">EPL\/IEPL<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/what-is-iplc\/\">Leased Line<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/connectivity-services\/eompls-pseudowire-service\/\">EoMPLS Pseudowire<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/jumbo-internet-exchange\/\">JumboIX<\/a> -->\r\n\r\n\r\n                                                  <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/ip-transit\/\">&#20114;&#32852;&#32593;&#31471;&#21475;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/direct-internet-access\/\">DIA, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/ix-transit\/\">&#20114;&#32852;&#32593;&#20132;&#25442;&#20013;&#24515;&#20132;&#36890;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/remote-dia\/\">&#36828;&#31243;&#20114;&#32852;&#32593;&#19987;&#32447;&#25509;&#20837;&#26381;&#21153;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/remote-ix\/\">&#36828;&#31243; IX, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/remote-ix-transit\/\">&#36828;&#31243;IX&#20256;&#36755;, <\/a>\r\n                                    <a href=\"javascript:void(0)\">&#36828;&#31243;IP&#20256;&#36755;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/managed-services\/dmms\/\">DDoS &#32233;&#35299; (DMMS), <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/ip-addresses\/\">IPv4\/IPv6 services<\/a>\r\n                              \r\n\r\n\r\n\r\n              <\/div>\r\n             \r\n            <\/div>\r\n            <div class=\"solutions-list__item--bottom\">\r\n              <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/connectivity-services\/\" class=\"underline --gray crcl\">&#20102;&#35299;&#26356;&#22810;<\/a>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n        <div class=\"col\">\r\n          <div class=\"solutions-list__item lift\">\r\n            <div class=\"solutions-list__item--body\">\r\n            <div class=\"--icon\"><img class=\"lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" data-src=\"\/wp-content\/uploads\/data-center-icon.svg\" alt=\"colo\"><\/div>\r\n              <div class=\"solutions-list__item-title\"><a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/datacenter-services\/\" class=\"stretched-link\">&#25968;&#25454;&#20013;&#24515;<\/a><\/div>\r\n\r\n              <div class=\"solutions-list__item-desc\">\r\n\r\n              <!-- <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/datacenter-services\/colocation\/\">Colocation<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/virtual-pop\/\">VPOP (Virtual POP)<\/a>, <a href=\"javascript:void(0)\">Cross Connect<\/a>, <a href=\"javascript:void(0)\">Metro Connect<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/datacenter-services\/remote-hands\/\">Remote\/Smart Hands<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/global-logistics\/ior-eor\/\">Logistics Export\/Import<\/a> -->\r\n\r\n\r\n                                                  <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/datacenter-services\/colocation\/\">&#23458;&#25143;&#20027;&#26426;&#25176;&#31649;&#26381;&#21153;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/internet-access\/virtual-pop\/\">&#34394;&#25311;&#20837;&#32593;&#28857;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/matrix4\/\">DC Matrix 4&#65288;&#38463;&#22982;&#26031;&#29305;&#20025;&#65289;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/k1\/\">DC Kermia 1&#65288;&#21033;&#39532;&#32034;&#23572;&#65289;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/hosting\/si\/\">DC San Isidro&#65288;&#21033;&#39532;&#65289;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/datacenter-services\/\">&#20132;&#21449;&#36830;&#25509;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/datacenter-services\/\">&#22478;&#22495;&#36830;&#25509;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/datacenter-services\/remote-hands\/\">&#36828;&#31243;&#25805;&#20316;&#26381;&#21153;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/global-logistics\/ior-eor\/\">IOR\/EOR, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/global-logistics\/warehouse-storage\/\">Warehouse Storage<\/a>\r\n                              \r\n\r\n\r\n\r\n              <\/div>\r\n            \r\n            <\/div>\r\n            <div class=\"solutions-list__item--bottom\">\r\n              <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/datacenter-services\/\" class=\"underline --gray crcl\">&#20102;&#35299;&#26356;&#22810;<\/a>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n        <div class=\"col\">\r\n          <div class=\"solutions-list__item lift\">\r\n            <div class=\"solutions-list__item--body\">\r\n            <div class=\"--icon\"><img class=\"lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" data-src=\"\/wp-content\/uploads\/colo-icon.svg\" alt=\"managed\"><\/div>\r\n              <div class=\"solutions-list__item-title\"><a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/datacenter-services\/dedicated-hosting\/\">&#19987;&#29992;&#25176;&#31649;&#26381;&#21153;<\/a><\/div>\r\n              <div class=\"solutions-list__item-desc\">\r\n\r\n              <!-- <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/locations\/\">Dedicated Server Hosting<\/a>, <a href=\"javascript:void(0)\">GPU<\/a>, <a href=\"javascript:void(0)\">AI<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/global-logistics\/warehouse-storage\/\">Storage<\/a>, <a href=\"javascript:void(0)\">Switch<\/a>, <a href=\"javascript:void(0)\">Router<\/a>, <a href=\"javascript:void(0)\">Firewall<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/datacenter-services\/edge-computing\/\">Edge Computing<\/a>, <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/business-solutions\/office-solutions\/remote-office\/\">Remote Office<\/a>  --> \r\n\r\n              \r\n\r\n                                                  <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/datacenter-services\/edge-computing\/\">&#36793;&#32536;&#35745;&#31639;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/office-solutions\/remote-office\/\">&#36828;&#31243;&#21150;&#20844;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/private-cloud\/\">&#31169;&#26377;&#20113;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/integration-services\/sd-wan-enabler\/\">SD-WAN &#25512;&#21160;&#32773;, <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/datacenter-services\/dedicated-hosting\/\">&#36719;&#20214;<\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/office-solutions\/cross-messenger\/\">XM (Cross messenger), <\/a>\r\n                                    <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/office-solutions\/lagblaster\/\">Lagblaster<\/a>\r\n                              \r\n\r\n\r\n                                            \r\n\r\n              <\/div>\r\n            \r\n            <\/div>\r\n            <div class=\"solutions-list__item--bottom\">\r\n              <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/network\/datacenter-services\/dedicated-hosting\/\" class=\"underline --gray crcl\">&#20102;&#35299;&#26356;&#22810;<\/a>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n\r\n            <p class=\"pt-5 mb-0 text-center\">\r\n        <!-- <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/request-a-quote\/\" class=\"btn-outline-primary --gray\">&#32034;&#21462;&#25253;&#20215;<\/a> -->\r\n        <a href=\"#\" class=\"btn-outline-primary --gray js_btn_request_form_all\">&#32034;&#21462;&#25253;&#20215;<\/a>\r\n      <\/p>\r\n   \r\n  <\/div>\r\n<\/div><div class=\"section\">\n<div class=\"inner\">\n<div class=\"subtitle\"><span>Overview<\/span><\/div>\n<h4>&#20851;&#20110; IP &#23376;&#32593;&#35745;&#31639;&#22120;<\/h4>\n<div class=\"accordion ip-subnet\" id=\"accordionPanelsStayOpenExample\">\n<div class=\"accordion-item\">\n<div class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#introduction\" aria-expanded=\"false\" aria-controls=\"introduction\">&#31616;&#20171;<\/button><\/div>\n<div id=\"introduction\" class=\"accordion-collapse collapse\">\n<div class=\"accordion-body\">\n<p>IP&#35745;&#31639;&#22120;&#26159;&#19968;&#20010;&#35745;&#31639;&#32593;&#32476;&#30340;&#24037;&#20855;&#12290;&#23427;&#20351;&#29992;&#32593;&#32476;&#31867;&#21035;&#12289;IP&#22320;&#22336;&#21644;&#23376;&#32593;&#25513;&#30721;&#26469;&#35745;&#31639;&#65292;&#24182;&#36865;&#22238;IPv4&#21644;IPv6&#23376;&#32593;&#30340;&#25968;&#25454;&#21015;&#34920;&#12290;<\/p>\n<p>IP&#35745;&#31639;&#22120;&#26159;&#19968;&#20010;&#26377;&#29992;&#30340;&#24037;&#20855;&#65292;&#23427;&#21487;&#20197;&#24110;&#21161;&#20174;&#26032;&#25163;&#21040;&#32463;&#39564;&#20016;&#23500;&#30340;IT&#19987;&#25165;&#25490;&#38500;&#25925;&#38556;&#21644;&#31649;&#29702;&#32593;&#32476;&#12290;<\/p>\n<p>IP&#35745;&#31639;&#22120;&#26159;&#19968;&#31181;&#21487;&#29992;&#20110;&#35745;&#31639;&#26356;&#22823;&#30340;&#32593;&#32476;&#20013;&#30340;&#23376;&#32593;&#25968;&#37327;&#12289;&#19968;&#20010;&#23376;&#32593;&#20013;&#21487;&#23481;&#32435;&#30340;&#20027;&#26426;&#25968;&#37327;&#65292;&#20197;&#21450;&#25152;&#26377;&#23376;&#32593;&#22823;&#23567;&#30340;&#24037;&#20855;&#12290; IP&#35745;&#31639;&#22120;&#20351;&#25105;&#20204;&#33021;&#22815;&#36827;&#34892;&#25152;&#26377;&#30340;&#36816;&#31639;&#65292;&#20363;&#22914;&#27595;&#39035;&#20154;&#25163;&#36827;&#34892;&#21313;&#36827;&#21046;&#21040;&#20108;&#36827;&#21046;&#30340;&#36716;&#25442;&#12290;IP&#35745;&#31639;&#22120;&#20351;&#32593;&#32476;&#21010;&#20998;&#20026;&#23376;&#32593;&#30340;&#36807;&#31243;&#21464;&#24471;&#26356;&#24555;&#12289;&#26356;&#23481;&#26131;&#12290;<\/p>\n<p>IP&#35745;&#31639;&#22120;&#21487;&#29992;&#20316;&#25490;&#38500;&#25925;&#38556;&#12289;&#35774;&#32622;&#32593;&#32476;&#22320;&#22336;&#25110;&#35774;&#35745;&#23376;&#32593;&#21644;&#36229;&#32593;&#12290;<\/p>\n<p>IPTP Networks&#30340;IP&#35745;&#31639;&#22120;&#36824;&#38468;&#24102;&#20102;&#19968;&#20010;&#38543;&#26426;&#30340;IP&#22320;&#22336;&#65292;&#20197;&#20934;&#22791;&#36827;&#34892;&#35745;&#31639;&#65292;&#36825;&#22312;&#25945;&#25480;&#20108;&#36827;&#21046;&#20540;&#12289;&#30740;&#31350;&#22914;&#20309;&#21010;&#20998;&#23376;&#32593;&#25110;&#36890;&#36807;CompTIA Network+&#32771;&#35797;&#26102;&#24456;&#26377;&#29992;&#12290;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"ipv4-sec2\" class=\"accordion-item targetDiv\">\n<div class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#use-ipv4-sec2\" aria-expanded=\"false\" aria-controls=\"use-ipv4-sec2\">&#22914;&#20309;&#20351;&#29992;<\/button><\/div>\n<div id=\"use-ipv4-sec2\" class=\"accordion-collapse collapse\">\n<div class=\"accordion-body\">\n<p class=\"fw-bold text-center\">IPTP Networks IPv4&#35745;&#31639;&#22120;&#30340;&#20351;&#29992;&#25351;&#21335;<\/p>\n<p><strong>&#20351;&#29992;IPv4&#35745;&#31639;&#22120;&#65306;<\/strong><\/p>\n<ul>\n<li>&#36873;&#25321;&#21512;&#24847;&#30340;&#32593;&#32476;&#31867;&#21035;&#65292;&#36825;&#26159;&#30001;&#23427;&#30340;&#31532;&#19968;&#20010;bits&#20915;&#23450;&#30340;&#65292;&#36890;&#36807;&#28857;&#20987;&#19977;&#20010;&#36873;&#39033;&#20013;&#30340;&#20219;&#20309;&#19968;&#20010;&#65306;A&#31867;&#65288;8 bits&#65289;&#12289;B&#31867;&#65288;16 bits&#65289;&#21644;C&#31867;&#65288;24 bits&#65289;&#12290;<\/li>\n<li>&#36755;&#20837;IP&#22320;&#22336;&#12290;&#31034;&#20363;&#20013;&#65292;IP&#22320;&#22336;&#24050;&#22635;&#20889;&#22312;&#21512;&#36866;&#30340;&#20301;&#32622;&#19978;&#65292;&#21487;&#20197;&#38543;&#26102;&#36827;&#34892;&#35745;&#31639;&#12290;<\/li>\n<li>&#26681;&#25454;&#20320;&#36873;&#25321;&#30340;&#32593;&#32476;&#31867;&#21035;&#65292;&#20174;&#19979;&#25289;&#21015;&#34920;&#20013;&#36873;&#25321;&#20320;&#30340;&#23376;&#32593;&#12290;<\/li>\n<li>&#28857;&#20987;&#35745;&#31639;&#25353;&#38062;&#65292;&#26597;&#30475;&#25152;&#26377;&#32593;&#32476;&#21644;IP&#22320;&#22336;&#20540;&#30340;&#32467;&#26524;&#12290;<\/li>\n<\/ul>\n<p>IPv4&#35745;&#31639;&#22120;&#25152;&#38656;&#30340;&#24517;&#35201;&#25968;&#25454;:<\/p>\n<p><strong>IP&#22320;&#22336;:<\/strong> IPv4&#22320;&#22336;&#20351;&#29992;32 bits&#22320;&#22336;&#65292;&#23427;&#25903;&#25345;232 &#20010;IP&#22320;&#22336;&#12290;IPv4&#26377;4&#32452;&#25968;&#23383; &ndash; &#20843;&#20301;&#25968;&#12290;&#27599;&#20010;&#20843;&#20301;&#25968;&#30340;&#33539;&#22260;&#22312;0&#21040;255&#20043;&#38388;&#65292;&#24182;&#29992;&#28857;&#65288;.&#65289;&#20998;&#24320;&#12290;<\/p>\n<p><strong>&#32593;&#32476;&#31561;&#32423;:<\/strong> &#32593;&#32476;&#20998;&#20026;A&#31867;&#12289;B&#31867;&#21644;C&#31867;&#12290;A&#31867;&#32593;&#32476;&#20351;&#29992;IP&#22320;&#22336;&#30340;&#21069;8 bits&#20316;&#20026;&#20854; &ldquo;&#32593;&#32476;&#37096;&#20998;&rdquo;&#65292;&#32780;B&#31867;&#20351;&#29992;&#21069;16 bits&#65292;C&#31867;&#20351;&#29992;&#21069;24 bits&#12290;<\/p>\n<p><strong>&#23376;&#32593;:<\/strong> &#23376;&#32593;&#21253;&#25324;&#20004;&#20010;&#37096;&#20998;&#65306;&#23376;&#32593;&#25513;&#30721;&#65292;&#32487;&#32780;&#26159;&#26080;&#31867;&#21035;&#22495;&#38388;&#65288;CIDR&#65289;&#31526;&#21495;&#12290;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"ipv6-sec2\" class=\"accordion-item targetDiv d-none\">\n<div class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#use-ipv6-sec2\" aria-expanded=\"false\" aria-controls=\"use-ipv6-sec2\">&#22914;&#20309;&#20351;&#29992;<\/button><\/div>\n<div id=\"use-ipv6-sec2\" class=\"accordion-collapse collapse\">\n<div class=\"accordion-body\">\n<p class=\"fw-bold\">IPTP Networks IPv6&#35745;&#31639;&#22120;&#30340;&#20351;&#29992;&#25351;&#21335;<\/p>\n<p><strong>&#20351;&#29992;IPv6 &#35745;&#31639;&#22120;:<\/strong><\/p>\n<ul>\n<li>1. &#36755;&#20837;IP&#22320;&#22336;&#12290;&#20363;&#22914;&#31034;&#20363;&#20013;&#20351;&#29992;&#30340;IPv6&#22320;&#22336;&#12290;<\/li>\n<li>2. &#20174;\/1&#21040;\/128&#30340;&#33539;&#22260;&#20869;&#36873;&#25321;&#21512;&#24847;&#30340;&#21069;&#32512;&#38271;&#24230;&#12290;<\/li>\n<li>3. &#23436;&#25104;&#21518;&#65292;&#20320;&#21487;&#20197;&#28857;&#20987;&#35745;&#31639;&#25353;&#38062;&#12290;<\/li>\n<\/ul>\n<p class=\"fw-bold\">IPv6&#35745;&#31639;&#22120;&#21482;&#38656;&#35201;&#20004;&#20010;&#29305;&#24615;&#65306;<\/p>\n<p><strong>&bull; &#21069;&#32512;&#38271;&#24230;:<\/strong> IPv6&#21069;&#32512;&#38271;&#24230;&#19982;IPv4&#23376;&#32593;&#25513;&#30721;&#30456;&#21516;&#12290;&#23427;&#26159;&#30001;&#22235;&#20010;&#20843;&#20301;&#25968;&#32452;&#25104;&#65292;&#30001;1&#21040;128&#20043;&#38388;&#30340;&#25972;&#25968;&#20889;&#25104;&#12290;<\/p>\n<p><strong>&bull; IP&#22320;&#22336;:<\/strong> IPv6 &#20197;&#21313;&#20845;&#36827;&#21046;&#26684;&#24335;&#32534;&#20889;&#65292;&#22312; &#20843;&#32452; 16 bits &#20043;&#38388;&#29992;&#20882;&#21495; (:) &#20998;&#38548;&#65292;&#24635;&#20849;&#26377;&#65288;8 x 16&#65289;128 bits&#12290;IPv6&#22320;&#22336;&#20026;x:x:x:x:x:x:x:x&#65292;&#33539;&#22260;&#20174;0000:0000:0000:0000:0000:0000:0000:0000 &#21040;ffff:ffff:ffff:ffff:ffff:ffff:ffff:ffff &#12290;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"ipv4-sec3\" class=\"accordion-item targetDiv\">\n<div class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#results-ipv4-sec3\" aria-expanded=\"false\" aria-controls=\"results-ipv4-sec3\">&#22914;&#20309;&#20351;&#29992;<\/button><\/div>\n<div id=\"results-ipv4-sec3\" class=\"accordion-collapse collapse\">\n<div class=\"accordion-body\">\n<p>IPv4&#35745;&#31639;&#22120;&#23558;&#20351;&#29992;&#36825;&#20123;&#20449;&#24687;&#26469;&#35745;&#31639;&#21644;&#26174;&#31034;&#20197;&#19979;&#32508;&#21512;&#20449;&#24687;&#65306;<\/p>\n<ul>\n<li><strong>&#32593;&#32476;&#22320;&#22336;:<\/strong> &#23376;&#32593;&#25513;&#30721;&#30340;&#31532;&#19968;&#37096;&#20998;&#65292;&#19982;IP&#22320;&#22336;&#30340;&#31532;&#19968;&#37096;&#20998;&#30456;&#21516;&#12290;<\/li>\n<li><strong>&#24191;&#25773;&#22320;&#22336;:<\/strong> &#23376;&#32593;&#20013;&#30340;&#26368;&#21518;&#19968;&#20010;&#22320;&#22336;&#12290;&#23427;&#29992;&#20110;&#21521;&#35813;&#23376;&#32593;&#30340;&#27599;&#21488;&#20027;&#26426;&#21457;&#36865;&#25968;&#25454;&#65288;&#24191;&#25773;&#65289;&#12290;<\/li>\n<li><strong>&#20027;&#26426;&#24635;&#25968;:<\/strong> &#32593;&#32476;&#19978;&#21487;&#29992;&#22320;&#22336;&#30340;&#24635;&#25968;&#12290;<\/li>\n<li><strong>&#21487;&#29992;&#30340;&#20027;&#26426;IP&#33539;&#22260;:<\/strong> &#36825;&#26159;&#25351;&#21487;&#20998;&#37197;&#32473;&#20027;&#26426;&#30340;IP&#22320;&#22336;&#33539;&#22260;&#12290;&#33539;&#22260;&#20174;&#32593;&#32476;&#22320;&#22336;&#20043;&#21518;&#24320;&#22987;&#65292;&#22312;&#24191;&#25773;&#22320;&#22336;&#20043;&#21069;&#32467;&#26463;&#12290;<\/li>\n<li><strong>&#21487;&#29992;&#30340;&#20027;&#26426;&#25968;&#37327;:<\/strong> &#21487;&#20998;&#37197;&#32473;&#20027;&#26426;&#30340;&#22320;&#22336;&#12290;&#22320;&#22336;&#24635;&#25968;&#19981;&#21253;&#25324;&#31532;&#19968;&#20010;&#22320;&#22336;&#65288;&#32593;&#32476;&#22320;&#22336;&#65289;&#21644;&#26368;&#21518;&#19968;&#20010;&#22320;&#22336;&#65288;&#24191;&#25773;&#22320;&#22336;&#65289;&#12290;<\/li>\n<li><strong>&#36890;&#37197;&#31526;&#25513;&#30721;:<\/strong> &#36825;&#26159;&#25351;&#23376;&#32593;&#25513;&#30721;&#39072;&#20498;&#30340;bits&#65292;&#19982;&#36335;&#30001;&#21327;&#35758;&#65288;OSPF&#65289;&#21644;&#35775;&#38382;&#25511;&#21046;&#21015;&#34920;&#65288;ACL&#65289;&#19968;&#21516;&#20351;&#29992;&#12290;<\/li>\n<li><strong>&#20108;&#36827;&#21046;&#23376;&#32593;&#25513;&#30721;:<\/strong> &#20108;&#36827;&#21046;&#26684;&#24335;&#30340;&#23376;&#32593;&#25513;&#30721;&#12290;<\/li>\n<li><strong>IP&#31867;&#21029;:<\/strong> IP&#22320;&#22336;&#34987;&#20998;&#20026;&#20116;&#31867;&#65292;&#20174;A&#31867;&#21040;E&#31867;&#12290;D&#31867;&#29992;&#20110;&#22810;&#36335;&#24191;&#25773;&#65292;E&#31867;&#21017;&#26159;&#23558;&#26469;&#20351;&#29992;&#12290;<\/li>\n<li><strong>&#26080;&#31867;&#22495;&#38388;&#36335;&#30001;&#65288;CIDR&#65289;&#31526;&#21495;:<\/strong> IP&#22320;&#22336;&#30001;&#19968;&#20123;bits&#65288;CIDR&#21495;&#30721;&#65289;&#32452;&#25104;&#65292;&#20013;&#38388;&#26377;&#27491;&#26012;&#26464;&#65288;\/&#65289;&#20316;&#20026;&#20998;&#38548;&#12290;<\/li>\n<li><strong>IP&#31867;&#22411;:<\/strong> &#26174;&#31034;&#35813;IP&#22320;&#22336;&#26159;&#20844;&#20849;&#30340;&#65288;&#20114;&#32852;&#32593;&#19978;&#65289;&#36824;&#26159;&#31169;&#20154;&#30340;&#65288;&#26412;&#22320;&#32593;&#32476;&#65289;&#12290;<\/li>\n<li><strong>&#20108;&#36827;&#21046;ID:<\/strong> &#20108;&#36827;&#21046;&#26684;&#24335;&#30340;IP&#22320;&#22336;&#21482;&#30001;0&#21644;1&#32452;&#25104;&#12290;<\/li>\n<li><strong>&#25972;&#25968;ID:<\/strong> &#25972;&#25968;&#26684;&#24335;&#30340;IP&#22320;&#22336;&#30001;0-9&#32452;&#25104;&#12290;<\/li>\n<li><strong>&#21313;&#20845;&#36827;&#21046;ID:<\/strong> &#21313;&#20845;&#36827;&#21046;&#26684;&#24335;&#30340;IP&#22320;&#22336;&#65292;&#20197; &laquo;0x &laquo;&#24320;&#22836;&#65292;&#30001;&#25968;&#23383;0-9&#21644;&#23383;&#27597;A-F&#32452;&#25104;&#12290;<\/li>\n<li><strong>In-addr.arpa:<\/strong> &#22495;&#21517;&#31995;&#32479;&#21453;&#21521;&#26597;&#35810;&#30340;&#32593;&#32476;&#21517;&#31216;&#12290;&#23427;&#26159;&#20498;&#24207;&#25490;&#21015;&#30340;IP&#22320;&#22336;&#12290;&#20363;&#22914;&#65292;&#24403;&#26597;&#35810;27.78.101.154&#30340;IP&#22320;&#22336;&#26102;&#65292;&#24471;&#21040;&#30340;&#32467;&#26524;&#26159;154.101.78.27.in-addr.arpa&#12290;<\/li>\n<li><strong>IPv4&#26144;&#23556;&#22320;&#22336;:<\/strong> &#36825;&#26159;&#25351;&#23558;&#19968;&#20010;32-bit&#30340;IPv4&#22320;&#22336;&#21576;&#29616;&#20026;&#19968;&#20010;128-bit&#30340;IPv6&#22320;&#22336;&#12290;&#23427;&#30340;&#26684;&#24335;&#20197;80&#20010; &laquo;0 &laquo;bits&#24320;&#22987;&#65292;&#28982;&#21518;&#26159;16bits&#30340; &laquo;1&raquo;&#65288;&#21313;&#20845;&#36827;&#21046;&#30340; &laquo;FFFF&raquo;&#65289;&#65292;&#38543;&#21518;&#26159;&#20197;&#21313;&#20845;&#36827;&#21046;&#26684;&#24335;&#20889;&#25104;&#30340;32-bit IPv4&#22320;&#22336;&#12290;<\/li>\n<li><strong>6to4&#21069;&#32512;:<\/strong> &#36825;&#26159;&#25351;&#23558;&#19968;&#20010;&#30001;IPv4&#25913;&#20889;&#25104;IPv6&#30340;&#26041;&#26696;&#12290;6to4&#22320;&#22336;&#24635;&#26159;&#20197;2002&#24320;&#22836;&#65292;&#38543;&#21518;&#26159;&#20197;&#21313;&#20845;&#36827;&#21046;&#20889;&#25104;&#30340;32-bit IPv4&#22320;&#22336;&#12290; IPv4&#35745;&#31639;&#22120;&#20250;&#25226;IP&#22320;&#22336;&#65288;&#32593;&#32476;&#22320;&#22336;&#12289;&#21487;&#29992;&#30340;&#20027;&#26426;&#33539;&#22260;&#12289;&#24191;&#25773;&#22320;&#22336;&#65289;&#25152;&#26377;&#21487;&#33021;&#20250;&#20986;&#29616;&#30340;&#32593;&#32476;&#25968;&#25454;&#20256;&#22238;&#12290;<\/li>\n<\/ul><\/div>\n<\/div>\n<\/div>\n<div id=\"ipv6-sec3\" class=\"accordion-item targetDiv d-none\">\n<div class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#results-ipv6-sec3\" aria-expanded=\"false\" aria-controls=\"results-ipv6-sec3\">&#22914;&#20309;&#20351;&#29992;<\/button><\/div>\n<div id=\"results-ipv6-sec3\" class=\"accordion-collapse collapse\">\n<div class=\"accordion-body\">\n<ul>\n<li><strong>IP&#22320;&#22336;:<\/strong> &#39038;&#21517;&#24605;&#20041;&#26174;&#31034;&#30340;&#26159;IP&#22320;&#22336;&#65292;&#20854;&#21069;&#32512;&#38271;&#24230;&#22823;&#22810;&#25968;&#26159;&#36890;&#36807;&#30465;&#30053; &rdquo;0&rdquo;&#26469;&#32553;&#30701;&#30340;&#12290;<\/li>\n<li><strong>&#23436;&#25972;&#30340;IP&#22320;&#22336;:<\/strong> IPv6&#22320;&#22336;&#20197;32-bits&#20840;&#20889;&#65292;&#27809;&#26377;&#32553;&#30701;&#38271;&#24230;&#12290;<\/li>\n<li><strong>IP&#22320;&#22336;&#24635;&#25968;:<\/strong> &#36825;&#26159;&#25351;IPv6&#32593;&#32476;&#19978;&#21487;&#29992;&#20027;&#26426;&#22320;&#22336;&#30340;&#24635;&#25968;&#12290;<\/li>\n<li><strong>&#24635;\/64&#32593;&#32476;:<\/strong> &#36825;&#26159;&#25351;&#32593;&#32476;&#19978;\/64&#23376;&#32593;&#30340;&#24635;&#25968;&#65288;&#22312;IPv6&#20013;&#65292;&#40664;&#35748;&#23376;&#32593;&#25513;&#30721;&#20026;\/64&#65289;&#12290;<\/li>\n<li><strong>&#32593;&#32476;:<\/strong> &#36825;&#26159;&#25351;&#32593;&#32476;&#22320;&#22336;&#65292;&#23427;&#26159;&#23376;&#32593;&#25513;&#30721;&#30340;&#21069;&#19977;&#32452;&#25968;&#23383;&#65288;&#21069;48 bits&#65289;&#65292;&#30001;&#26080;&#31867;&#21035;&#22495;&#38388;&#65288;CIDR&#65289;&#31526;&#21495;&#32452;&#25104;&#12290;<\/li>\n<li><strong>IP&#33539;&#22260;:<\/strong> &#21487;&#20998;&#37197;&#32473;&#20027;&#26426;&#30340;IPv6&#22320;&#22336;&#30340;&#33539;&#22260;&#12290;<\/li>\n<\/ul><\/div>\n<\/div>\n<\/div>\n<div class=\"accordion-item\">\n<div class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#subneting\" aria-expanded=\"false\" aria-controls=\"subneting\">&#23376;&#32593;&#21010;&#20998;<\/button><\/div>\n<div id=\"subneting\" class=\"accordion-collapse collapse\">\n<div class=\"accordion-body\">\n<p>&#23376;&#32593;&#65292;&#25110;&#31216;&#20026;&#23376;&#32593;&#32476;&#65292;&#26159;IP&#32593;&#32476;&#30340;&#19968;&#20010;&#32454;&#20998;&#37096;&#20998;&#12290;&#24403;&#19968;&#20010;&#32593;&#32476;&#34987;&#25286;&#20998;&#25104;&#20026;&#20004;&#20010;&#25110;&#22810;&#20010;&#30456;&#36830;&#30340;&#32593;&#32476;&#26102;&#65292;&#20415;&#24418;&#25104;&#23376;&#32593;&#12290;<\/p>\n<p>&#23376;&#32593;&#21010;&#20998;&#26159;&#25351;&#24314;&#31435;&#23376;&#32593;&#12290;&#23376;&#32593;&#30340;&#20351;&#29992;&#26159;&#20026;&#20102;&#23613;&#37327;&#20943;&#23569;&#27969;&#37327;&#21644;&#25552;&#21319;&#32593;&#32476;&#36895;&#24230;&#12290;&#24403;&#25226;&#19968;&#20010;&#22823;&#32593;&#32476;&#21010;&#20998;&#25104;&#26080;&#25968;&#20010;&#23567;&#32593;&#32476;&#26102;&#65292;&#32593;&#32476;&#36895;&#24230;&#23558;&#24471;&#20197;&#25552;&#21319;&#65292;&#20174;&#32780;&#20943;&#23569;&#38656;&#35201;&#23450;&#20301;&#20110;&#21333;&#20010;&#35774;&#22791;&#30340;&#36335;&#24452;&#25968;&#37327;&#12290;<\/p>\n<p>&#35774;&#22791;&#20063;&#26377;&#19968;&#20010;&#23376;&#32593;&#25513;&#30721;&#65292;&#23427;&#33021;&#20998;&#36776;&#20986;IP&#22320;&#22336;&#20219;&#20309;&#19968;&#20010;&#37096;&#20998;&#26159;&#23646;&#20110;&#32593;&#32476;&#36824;&#26159;&#35774;&#22791;&#30340;&#12290;&#20026;&#20102;&#36830;&#25509;&#21040;&#20854;&#20182;&#32593;&#32476;&#65292;&#36825;&#38656;&#35201;&#19968;&#20010;&#32593;&#20851;&#12290;&#24403;&#19968;&#20010;&#35774;&#22791;&#19982;&#19981;&#21516;&#32593;&#32476;&#19978;&#30340;&#21478;&#19968;&#20010;&#35774;&#22791;&#36827;&#34892;&#36890;&#35759;&#26102;&#65292;&#20449;&#24687;&#20808;&#26159;&#34987;&#36335;&#30001;&#21040;&#32593;&#20851;&#65292;&#28982;&#21518;&#25165;&#21040;&#36798;&#26368;&#32456;&#30446;&#30340;&#22320;&#12290;<\/p>\n<p>&#20114;&#32852;&#32593;&#21327;&#35758;&#65288;IP&#65289;&#26159;&#19968;&#31181;&#25968;&#25454;&#20256;&#36755;&#21327;&#35758;&#65292;&#23427;&#20801;&#35768;&#35774;&#22791;&#22312;&#20114;&#32852;&#32593;&#19978;&#36827;&#34892;&#36890;&#35759;&#12290;IPv4&#26159;&#19968;&#20010;32-bit&#30340;&#22320;&#22336;&#65292;&#32780;IPv6&#21017;&#26159;128-bit&#12290;&#27599;&#20010;&#35774;&#22791;&#37117;&#26377;&#33258;&#24049;&#30340;IP&#22320;&#22336;&#65292;&#35813;&#22320;&#22336;&#20174;IPv4&#25110;IPv6&#38598;&#21306;&#20013;&#25277;&#21462;&#65292;&#30001;&#20004;&#37096;&#20998;&#32452;&#25104;&#65306;&#20027;&#26426;&#65288;&#23458;&#25143;&#65289;&#21644;&#32593;&#32476;&#65288;&#26381;&#21153;&#22120;&#65289;&#12290;<\/p>\n<p>&#32593;&#32476;&#37096;&#20998;&#35782;&#21035;&#20026;&#19968;&#20010;&#29305;&#23450;&#30340;&#32593;&#32476;&#65292;&#20027;&#26426;&#37096;&#20998;&#35782;&#21035;&#20026;&#33410;&#28857;&#65288;&#19968;&#20010;&#35774;&#22791;&#65289;&#12290;&#26080;&#31867;&#22495;&#38388;&#36335;&#30001;&#65288;CIDR&#65289;&#20026;&#32593;&#32476;&#21644;&#35774;&#22791;&#20998;&#37197;&#29420;&#19968;&#26080;&#20108;&#30340;ID&#12290;&#32593;&#32476;&#22320;&#22336;&#23545;&#20110;&#23376;&#32593;&#20013;&#30340;&#25152;&#26377;&#20027;&#26426;&#32780;&#35328;&#37117;&#26159;&#19968;&#26679;&#30340;&#65292;&#32780;&#20027;&#26426;&#22320;&#22336;&#21017;&#26159;&#29420;&#29305;&#30340;&#12290;<\/p>\n<p>&#19968;&#20010;IP&#22320;&#22336;&#30001;&#26080;&#31867;&#22495;&#38388;&#36335;&#30001;&#65288;CIDR&#65289;&#34920;&#31034;&#65292;&#20854;IP&#22320;&#22336;&#19982;&#26222;&#36890;&#30340;IP&#22320;&#22336;&#30456;&#20284;&#65292;&#21482;&#26159;&#23427;&#20197;&#26012;&#32447;&#65288;&#65295;&#65289;&#21644;&#19968;&#20010;&#25968;&#23383;&#32467;&#23614;&#65292;&#31216;&#20026;IP&#32593;&#32476;&#21069;&#32512;&#12290; &#23376;&#32593;&#26377;&#19977;&#20010;&#26368;&#24120;&#29992;&#30340;&#31867;&#21035;&#65292;&#20998;&#21035;&#26159;A&#31867;&#12289;B&#31867;&#21644;C&#31867;&#12290;&#27599;&#20010;&#31867;&#21035;&#28041;&#21450;&#29305;&#23450;&#30340;IP&#22320;&#22336;&#33539;&#22260;&#65292;&#24182;&#19988;&#25317;&#26377;&#19968;&#20010;&#40664;&#35748;&#30340;&#23376;&#32593;&#25513;&#30721;&#12290;<\/p>\n<p>&#19979;&#34920;&#25552;&#20379;&#20102;&#26377;&#20851;IPv4&#23376;&#32593;&#30340;&#20449;&#24687;&#65306;<\/p>\n<div class=\"row row-cols-1 row-cols-md-2 gx-4 gy-2\">\n<div class=\"col\">\n<div class=\"text-primary table-title-1\">A &#31867;<\/div>\n<table class=\"table table-sm d-none d-md-table\">\n<thead>\n<tr>\n<th scope=\"col\">Prefix size\/<br>CIDR Notation<\/th>\n<th scope=\"col\">&#32593;&#32476;&#25513;&#30721;<\/th>\n<th scope=\"col\">&#21487;&#29992;&#30340;&#20027;&#26426;&#25968;&#37327;<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th scope=\"row\">1<\/th>\n<td>128.0.0.0<\/td>\n<td>2,147,483,646<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">2<\/th>\n<td>192.0.0.0<\/td>\n<td>1,073,741,822<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">3<\/th>\n<td>224.0.0.0<\/td>\n<td>536,870,910<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">4<\/th>\n<td>240.0.0.0<\/td>\n<td>268,435,454<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">5<\/th>\n<td>248.0.0.0<\/td>\n<td>134,217,726<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">6<\/th>\n<td>252.0.0.0<\/td>\n<td>67,108,862<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">7<\/th>\n<td>254.0.0.0<\/td>\n<td>33,554,430<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"table table-sm d-md-none\">\n<thead>\n<tr>\n<th scope=\"col\">Prefix size\/<br>CIDR Notation<\/th>\n<th scope=\"col\">&#32593;&#32476;&#25513;&#30721;<\/th>\n<th scope=\"col\">&#21487;&#29992;&#30340;&#20027;&#26426;&#25968;&#37327;<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th scope=\"row\">1<\/th>\n<td>128.0.0.0<\/td>\n<td>2,147,483,646<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">2<\/th>\n<td>192.0.0.0<\/td>\n<td>1,073,741,822<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">3<\/th>\n<td>224.0.0.0<\/td>\n<td>536,870,910<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">4<\/th>\n<td>240.0.0.0<\/td>\n<td>268,435,454<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">5<\/th>\n<td>248.0.0.0<\/td>\n<td>134,217,726<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">6<\/th>\n<td>252.0.0.0<\/td>\n<td>67,108,862<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">7<\/th>\n<td>254.0.0.0<\/td>\n<td>33,554,430<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">8<\/th>\n<td>255.0.0.0<\/td>\n<td>16,777,214<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">9<\/th>\n<td>255.128.0.0<\/td>\n<td>8,388,606<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">10<\/th>\n<td>255.192.0.0<\/td>\n<td>4,194,302<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">11<\/th>\n<td>255.224.0.0<\/td>\n<td>2,097,150<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">12<\/th>\n<td>255.240.0.0<\/td>\n<td>1,048,574<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">13<\/th>\n<td>255.248.0.0<\/td>\n<td>524,286<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">14<\/th>\n<td>255.252.0.0<\/td>\n<td>262,142<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">15<\/th>\n<td>255.254.0.0<\/td>\n<td>131,070<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<div class=\"col\">\n<div class=\"text-primary table-title-1 d-none d-md-block\">A &#31867;<\/div>\n<table class=\"table table-sm d-none d-md-table\">\n<thead>\n<tr>\n<th scope=\"col\">Prefix size\/<br>CIDR Notation<\/th>\n<th scope=\"col\">&#32593;&#32476;&#25513;&#30721;<\/th>\n<th scope=\"col\">&#21487;&#29992;&#30340;&#20027;&#26426;&#25968;&#37327;<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th scope=\"row\">8<\/th>\n<td>255.0.0.0<\/td>\n<td>16,777,214<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">9<\/th>\n<td>255.128.0.0<\/td>\n<td>8,388,606<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">10<\/th>\n<td>255.192.0.0<\/td>\n<td>4,194,302<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">11<\/th>\n<td>255.224.0.0<\/td>\n<td>2,097,150<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">12<\/th>\n<td>255.240.0.0<\/td>\n<td>1,048,574<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">13<\/th>\n<td>255.248.0.0<\/td>\n<td>524,286<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">14<\/th>\n<td>255.252.0.0<\/td>\n<td>262,142<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">15<\/th>\n<td>255.254.0.0<\/td>\n<td>131,070<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<div class=\"col\">\n<div class=\"text-primary table-title-1\">B &#31867;<\/div>\n<table class=\"table table-sm\">\n<thead>\n<tr>\n<th scope=\"col\">Prefix size\/<br>CIDR Notation<\/th>\n<th scope=\"col\">&#32593;&#32476;&#25513;&#30721;<\/th>\n<th scope=\"col\">&#21487;&#29992;&#30340;&#20027;&#26426;&#25968;&#37327;<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th scope=\"row\">16<\/th>\n<td>255.255.0.0<\/td>\n<td>65,534<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">17<\/th>\n<td>255.255.128.0<\/td>\n<td>32,766<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">18<\/th>\n<td>255.255.192.0<\/td>\n<td>16,382<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">19<\/th>\n<td>255.255.224.0<\/td>\n<td>8,190<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">20<\/th>\n<td>255.255.240.0<\/td>\n<td>4,094<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">21<\/th>\n<td>255.255.248.0<\/td>\n<td>2,046<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">22<\/th>\n<td>255.255.252.0<\/td>\n<td>1,022<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">23<\/th>\n<td>255.255.254.0<\/td>\n<td>510<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<div class=\"col\">\n<div class=\"text-primary table-title-1\">C &#31867;<\/div>\n<table class=\"table table-sm\">\n<thead>\n<tr>\n<th scope=\"col\">Prefix size\/<br>CIDR Notation<\/th>\n<th scope=\"col\">&#32593;&#32476;&#25513;&#30721;<\/th>\n<th scope=\"col\">&#21487;&#29992;&#30340;&#20027;&#26426;&#25968;&#37327;<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th scope=\"row\">24<\/th>\n<td>255.255.255.0<\/td>\n<td>254<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">25<\/th>\n<td>255.255.255.128<\/td>\n<td>126<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">26<\/th>\n<td>255.255.255.192<\/td>\n<td>62<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">27<\/th>\n<td>255.255.255.224<\/td>\n<td>30<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">28<\/th>\n<td>255.255.255.240<\/td>\n<td>14<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">29<\/th>\n<td>255.255.255.248<\/td>\n<td>6<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">30<\/th>\n<td>255.255.255.252<\/td>\n<td>2<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">31<\/th>\n<td>255.255.255.254<\/td>\n<td>0<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">32<\/th>\n<td>255.255.255.255<\/td>\n<td>0<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h4>&#38656;&#35201;&#24110;&#24537;&#65311;<\/h4>\n<p>&#22914;&#26524;&#24744;&#26377;&#20219;&#20309;&#30097;&#38382;&#65292;&#35831;&#30005;&#37038;&#33267; <a class=\"underline\"><span class=\"sp-user\">cs<\/span><span class=\"sp-domain\">iptp.net<\/span><\/a>&#65292;&#25110;&#20351;&#29992;&#32593;&#39029;&#21491;&#19979;&#26041; <a href=\"javascript:popupchat()\" class=\"underline\">Live Assistant<\/a> &#25353;&#38062;&#19982;&#25105;&#20204;&#32852;&#31995;&#12290;<\/p>\n<\/div>\n<\/div><div class=\"section\">\n<div class=\"inner\" style=\"padding-bottom: 30px;\">\n<div class=\"subtitle text-center\"><span>IPTP&#24037;&#20855;<\/span><\/div>\n<h2 class=\"text-center\">&#24744;&#21487;&#33021;&#38656;&#35201;&#30340; IPTP &#24037;&#20855;<\/h2>\n<\/div>\n<div class=\"row row-cols-2 row-cols-md-3 row-cols-lg-4 g-3 g-lg-4 justify-content-center iptp-tool-list pb-5\">\n<div class=\"col\">\n<div class=\"iptp-tool\">\n<div class=\"iptp-tool--body\">\n<div class=\"iptp-tool-title\">IP Subnet Calculator\n<div class=\"iptp-tool-icon\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"\" data-src=\"\/wp-content\/uploads\/ipcalc.svg\" class=\"lazy\"><\/div>\n<\/div>\n<div class=\"iptp-tool-desc\">&#19968;&#20010;&#24037;&#20855;&#33719;&#21462;IP&#22320;&#22336;&#21644;&#32593;&#32476;&#25513;&#30721;&#24182;&#35745;&#31639;&#29983;&#25104;&#30340;&#24191;&#25773;&#65292;&#32593;&#32476;&#65292; &#36890;&#37197;&#31526;&#25513;&#30721;&#21644;&#20027;&#26426;&#33539;&#22260;&#12290;<\/div>\n<\/div>\n<div class=\"iptp-tool--bottom\">\n          <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/iptp-tools\/ip-calculator\/\" class=\"stretched-link --gray\">Calculate<\/a>\n        <\/div>\n<\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"iptp-tool\">\n<div class=\"iptp-tool--body\">\n<div class=\"iptp-tool-title\">Best Path\n<div class=\"iptp-tool-icon\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"Best Path\" data-src=\"\/wp-content\/uploads\/bestpath.svg\" class=\"lazy\"><\/div>\n<\/div>\n<div class=\"iptp-tool-desc\">&#27492;&#24037;&#20855;&#23558;&#21521;&#24744;&#23637;&#31034;&#25105;&#20204;&#30340;&#23384;&#22312;&#28857;&#20043;&#38388;&#30340;&#24310;&#36831;&#21644;&#26368;&#20339;&#36335;&#30001;&#36335;&#24452;&#12290;<\/div>\n<\/div>\n<div class=\"iptp-tool--bottom\">\n          <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/iptp-tools\/best-path\/\" class=\"stretched-link --gray\">Calculate<\/a>\n        <\/div>\n<\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"iptp-tool\">\n<div class=\"iptp-tool--body\">\n<div class=\"iptp-tool-title\">Uptime Calculator\n<div class=\"iptp-tool-icon\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"Uptime Calculator\" data-src=\"\/wp-content\/uploads\/uptime.svg\" class=\"lazy\"><\/div>\n<\/div>\n<div class=\"iptp-tool-desc\">&#27491;&#24120;&#36816;&#34892;&#26102;&#38388;&#35745;&#31639;&#22120;&#25552;&#20379;&#20102;&#19968;&#31181;&#31616;&#21333;&#30340;&#26041;&#27861;&#26469;&#26681;&#25454;&#25552;&#20379;&#30340;&#27491;&#24120;&#36816;&#34892;&#26102;&#38388;&#30334;&#20998;&#27604;&#26469;&#35745;&#31639;&#20572;&#26426;&#26102;&#38388;&#27941;&#36148;.<\/div>\n<\/div>\n<div class=\"iptp-tool--bottom\">\n          <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/iptp-tools\/uptime-calculator\/\" class=\"stretched-link --gray\">Calculate<\/a>\n        <\/div>\n<\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"iptp-tool\">\n<div class=\"iptp-tool--body\">\n<div class=\"iptp-tool-title\">IXP Compare\n<div class=\"iptp-tool-icon\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"IXP Compare\" data-src=\"\/wp-content\/uploads\/ixs.svg\" class=\"lazy\"><\/div>\n<\/div>\n<div class=\"iptp-tool-desc\">&#22312;&#20004;&#20010; Internet Exchange &#20043;&#38388;&#21019;&#24314;&#35814;&#32454;&#30340;&#22270;&#24418;&#27604;&#36739;.<\/div>\n<\/div>\n<div class=\"iptp-tool--bottom\">\n          <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/iptp-tools\/ixp-compare\/\" class=\"stretched-link --gray\">Get compared<\/a>\n        <\/div>\n<\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"iptp-tool\">\n<div class=\"iptp-tool--body\">\n<div class=\"iptp-tool-title\">Looking Glass\n<div class=\"iptp-tool-icon\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"Looking Glass\" data-src=\"\/wp-content\/uploads\/lookingglass.svg\" class=\"lazy\"><\/div>\n<\/div>\n<div class=\"iptp-tool-desc\">&#26381;&#21153;&#21487;&#21327;&#21161;&#24744;&#35775;&#38382;&#25105;&#20204;&#30340;&#36335;&#30001;&#20449;&#24687;&#12290;<\/div>\n<\/div>\n<div class=\"iptp-tool--bottom\">\n          <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/iptp-tools\/lg\/\" class=\"stretched-link --gray\">&#20102;&#35299;&#26356;&#22810;<\/a>\n        <\/div>\n<\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"iptp-tool\">\n<div class=\"iptp-tool--body\">\n<div class=\"iptp-tool-title\">Bandwidth Test\n<div class=\"iptp-tool-icon\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"Bandwidth Test\" data-src=\"\/wp-content\/uploads\/bandwidth.svg\" class=\"lazy\"><\/div>\n<\/div>\n<div class=\"iptp-tool-desc\">&#22312;&#36825;&#37324;&#24744;&#21487;&#20197;&#20102;&#35299;&#25105;&#20204;&#32593;&#32476;&#30340;&#24102;&#23485;&#12290;<\/div>\n<\/div>\n<div class=\"iptp-tool--bottom\">\n          <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/iptp-tools\/bandwidth-test\/\" class=\"stretched-link --gray\">Check out<\/a>\n        <\/div>\n<\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"iptp-tool\">\n<div class=\"iptp-tool--body\">\n<div class=\"iptp-tool-title\">Weathermap\n<div class=\"iptp-tool-icon\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"Weathermap\" data-src=\"\/wp-content\/uploads\/weatherm.svg\" class=\"lazy\"><\/div>\n<\/div>\n<div class=\"iptp-tool-desc\">&#25105;&#20204;&#30340;&#20840;&#29699;&#32593;&#32476;&#23454;&#26102;&#22320;&#22270;&#12290;<\/div>\n<\/div>\n<div class=\"iptp-tool--bottom\">\n          <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/iptp-tools\/weathermap\/\" class=\"stretched-link --gray\">Check<\/a>\n        <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div class=\"section section-banner\">\r\n    <div class=\"inner text-center\">\r\n            <div class=\"subtitle\"><span>&#35831;&#27714;&#25253;&#20215;<\/span><\/div>\r\n                <h2>Ready to Get Started?<\/h2>\r\n                <p>&#25105;&#20204;&#30340;&#19987;&#23478;&#23558;&#24456;&#24555;&#19982;&#24744;&#32852;&#31995;<\/p>\r\n                <p class=\"pt-3 mb-0\">\r\n            <!-- <a href=\"https:\/\/web.la.iptp.net\/zh_CN\/request-a-quote\/?post=280\" class=\"btn-primary-rounded-pill d-inline-block\">&#35831;&#27714;&#25253;&#20215;<\/a> -->\r\n            <a href=\"#\" class=\"btn-primary-rounded-pill d-inline-block js_btn_request_form_all\">&#35831;&#27714;&#25253;&#20215;<\/a>\r\n        <\/p>\r\n        <\/div>\r\n<\/div>\n","protected":false},"excerpt":{"rendered":"[wce_code id=20]\n<p>         IPv4 subnet Calculator <\/p>\n<p>         &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":276,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-ipcalculator-new.php","meta":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/web.la.iptp.net\/zh_CN\/wp-json\/wp\/v2\/pages\/280"}],"collection":[{"href":"https:\/\/web.la.iptp.net\/zh_CN\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/web.la.iptp.net\/zh_CN\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/zh_CN\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/zh_CN\/wp-json\/wp\/v2\/comments?post=280"}],"version-history":[{"count":608,"href":"https:\/\/web.la.iptp.net\/zh_CN\/wp-json\/wp\/v2\/pages\/280\/revisions"}],"predecessor-version":[{"id":23386,"href":"https:\/\/web.la.iptp.net\/zh_CN\/wp-json\/wp\/v2\/pages\/280\/revisions\/23386"}],"up":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/zh_CN\/wp-json\/wp\/v2\/pages\/276"}],"wp:attachment":[{"href":"https:\/\/web.la.iptp.net\/zh_CN\/wp-json\/wp\/v2\/media?parent=280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}