{"id":73,"date":"2019-12-10T11:53:07","date_gmt":"2019-12-10T08:53:07","guid":{"rendered":"https:\/\/web-mng.iptp.com\/?page_id=73"},"modified":"2023-11-29T23:45:12","modified_gmt":"2023-11-29T20:45:12","slug":"company","status":"publish","type":"page","link":"https:\/\/web.la.iptp.net\/pt_PT\/company\/","title":{"rendered":"A Companhia"},"content":{"rendered":"<p>Nosso objetivo &eacute; ajudar as empresas a resolver todos os seus desafios neste mundo de TI em r&aacute;pida mudan&ccedil;a. Sendo nossa principal prioridade, estar dispon&iacute;vel no momento certo, no lugar certo e com as solu&ccedil;&otilde;es certas, que s&atilde;o perfeitamente adaptadas de acordo com os requisitos individuais exclusivos. Temos orgulho em chamar nossos parceiros e clientes de amigos e estamos muito felizes que nossa associa&ccedil;&atilde;o lhes d&ecirc; uma grande satisfa&ccedil;&atilde;o.<\/p><p>Desde a sua cria&ccedil;&atilde;o em 1996, a equipe do IPTP ajudou cerca de [clients] clientes corporativos em todo o mundo, em sua jornada para a transforma&ccedil;&atilde;o digital, agilizando seus neg&oacute;cios, reduzindo custos, expandindo e protegendo sua infraestrutura e antecipando a concorr&ecirc;ncia. Desde a sua funda&ccedil;&atilde;o, a empresa continuou com consist&ecirc;ncia, trabalho duro e inova&ccedil;&atilde;o. Agora, crescemos e nos tornamos um <a href=\"https:\/\/web.la.iptp.net\/pt_PT\/company\/iptp-networks-in-numbers\/\">importante grupo internacional e uma organiza&ccedil;&atilde;o de classe mundial<\/a>. Operamos um backbone global, como um Provedor de Servi&ccedil;os de Internet (ISP) de Tier-1, que fornece conectividade atrav&eacute;s de mais de 228 centros de dados ON-NET em todo o mundo.<\/p><p>Nesta &aacute;rea, voc&ecirc; encontrar&aacute; as seguintes p&aacute;ginas: <\/p><li><a href=\"https:\/\/web.la.iptp.net\/pt_PT\/company\/iptp-networks-in-numbers\/\">Nossas realiza&ccedil;&otilde;es em n&uacute;meros<\/a><\/li><li><a href=\"https:\/\/web.la.iptp.net\/pt_PT\/company\/meet-our-team\/\">Conhe&ccedil;a Nossa Equipe<\/a><\/li><li><a href=\"https:\/\/web.la.iptp.net\/pt_PT\/careers\/\">Carreiras<\/a><\/li><li><a href=\"https:\/\/web.la.iptp.net\/pt_PT\/company\/contacts\/\">Contatos<\/a><\/li>\n","protected":false},"excerpt":{"rendered":"<p>\n Information will be added soon <\/p>\n<p> &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/pages\/73"}],"collection":[{"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/comments?post=73"}],"version-history":[{"count":225,"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/pages\/73\/revisions"}],"predecessor-version":[{"id":28675,"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/pages\/73\/revisions\/28675"}],"wp:attachment":[{"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/media?parent=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}