{"id":25218,"date":"2023-02-02T05:17:01","date_gmt":"2023-02-02T02:17:01","guid":{"rendered":"https:\/\/web-dev.iptp.net\/?page_id=25218"},"modified":"2026-04-17T06:39:17","modified_gmt":"2026-04-17T03:39:17","slug":"best-path-app","status":"publish","type":"page","link":"https:\/\/web.la.iptp.net\/pt_PT\/best-path-app\/","title":{"rendered":"APLICATIVO BEST PATH"},"content":{"rendered":"<section style=\"font-size:15px\">\n<h3 class=\"fs-6 text-primary\">VEN&Ccedil;A A CONCORR&Ecirc;NCIA E MOSTRE SUA REDE SUPERIOR COM LAT&Ecirc;NCIA PRECISA E ROTAS IDEAIS.<\/h3>\n<p>   Um mapa de rede complexo cheio de rotas intrincadas que se entrela&ccedil;am pode impressionar seus clientes, mas n&atilde;o exatamente dar a eles uma &oacute;tima experi&ecirc;ncia. <\/p>\n<p>   Que tal surpreender e criar uma experi&ecirc;ncia perfeita com maior conforto para seus clientes?<\/p>\n<h3 class=\"fs-6 text-primary\">OBTENHA A VANTAGEM DO PIONEIRISMO COM NOSSA SOLU&Ccedil;&Atilde;O EXCLUSIVA E PIONEIRA NO MERCADO: O APLICATIVO BEST PATH.<\/h3>\n<p>   O Best Path &eacute; um aplicativo pioneiro da IPTP Networks que ilustra as lat&ecirc;ncias corretas entre todos os n&oacute;s da sua rede. <\/p>\n<p>   O aplicativo Best Path &eacute; uma solu&ccedil;&atilde;o personalizada que divide seu mapa de rede generalizado em dados detalhados. Ao contr&aacute;rio do mapa de rede que representa cada caminho e n&oacute;, o aplicativo Best Path o mant&eacute;m no m&iacute;nimo, com apenas os pontos de presen&ccedil;a (POP) e cabos necess&aacute;rios.<\/p>\n<p class=\"text-center\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"bestpathillustration\" class=\"img-fluid w-100 rounded lazy\" data-src=\"\/wp-content\/uploads\/bestpathillustration.png\"><\/p>\n<h2 class=\"fs-6 text-secondary\">POR QUE O APLICATIVO BEST PATH?<\/h2>\n<p>   Sua empresa tem uma rede fant&aacute;stica, um backbone extenso e um sistema de cabeamento diversificado, mas voc&ecirc; est&aacute; tendo dificuldades para apresent&aacute;-lo a seus parceiros e clientes? <\/p>\n<p>   Sua equipe costuma se esfor&ccedil;ar para acompanhar sua rede em constante expans&atilde;o? <\/p>\n<p>   O aplicativo IPTP Networks Best Path &eacute; uma ferramenta especial que permite que suas equipes estejam sintonizadas com rela&ccedil;&atilde;o &agrave; rede e conectividades de sua empresa.<\/p>\n<ul class=\"list-marker--primary mb-5\">\n<li><strong class=\"text-primary\">Equipe t&eacute;cnica:<\/strong> voc&ecirc; s&oacute; precisar&aacute; atualizar o banco de dados e o aplicativo se ajustar&aacute; automaticamente, permitindo que todos os n&atilde;o t&eacute;cnicos acompanhem as &uacute;ltimas altera&ccedil;&otilde;es na rede.<\/li>\n<li><strong class=\"text-primary\">Equipes de marketing, atendimento e vendas:<\/strong> Os detalhes mais precisos sobre a rede podem ser facilmente apresentados ao p&uacute;blico, o backbone, os cabos, as conex&otilde;es e a lat&ecirc;ncia de qualquer rota sem que seja necess&aacute;rio memoriz&aacute;-los todos.<\/li>\n<li><strong class=\"text-primary\">Parceiros e clientes de peering:<\/strong> isso fornecer&aacute; um m&eacute;todo mais conveniente e transparente de visualizar sua rede.<\/li>\n<\/ul>\n<div class=\"bg-primary bp-img1-wrap text-white rounded bp-img-wrap p-3 px-lg-4 py-lg-1 row g-4 mx-auto text-center text-md-start my-5\">\n<div class=\"col-12 col-md-3\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"\" class=\"bp-img1 lazy\" data-src=\"\/wp-content\/uploads\/bpcompatillustr.svg\"><\/div>\n<div class=\"col-12 col-md-9 ps-lg-5\">O Best Path &eacute; compat&iacute;vel com todos os dispositivos e est&aacute; dispon&iacute;vel para usu&aacute;rios da Web (Windows, Mac, Linux), Android e iOS.<\/div>\n<\/div>\n<h2 class=\"fs-6 text-secondary pt-4\">FUNCIONALIDADES DO APP BEST PATH<\/h2>\n<p>O aplicativo Best Path consiste em 2 elementos principais, incluindo a tabela de informa&ccedil;&otilde;es da rota e o mapa visual.<\/p>\n<div class=\"row g-4 mb-5 mt-3\">\n<div class=\"col-12 col-md-6\">\n<div class=\"bp-box rounded h-100\">\n<div class=\"bp-box--header rounded-top\">\n<div><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"\" class=\"bp-box--icon lazy\" data-src=\"\/wp-content\/uploads\/routedata.svg\"><\/div>\n<h4 class=\"bp-box--title\">DADOS DE ROTA<\/h4>\n<\/div>\n<div class=\"p-3 p-lg-4\">\n<p>O aplicativo Best Path consiste em 2 elementos principais, incluindo a tabela de informa&ccedil;&otilde;es da rota e o mapa visual:<\/p>\n<ul>\n<li class=\"mb-1\">Os POPs no caminho entre os locais escolhidos<\/li>\n<li class=\"mb-1\">A lat&ecirc;ncia e o RTD entre cada n&oacute;.<\/li>\n<li class=\"mb-1\">O cabo usado na estrada.<\/li>\n<li class=\"mb-1\">A unidade m&aacute;xima de transfer&ecirc;ncia (MTU).<\/li>\n<\/ul><\/div>\n<\/div>\n<\/div>\n<div class=\"col-12 col-md-6\">\n<div class=\"bp-box rounded h-100\">\n<div class=\"bp-box--header rounded-top\">\n<div><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"\" class=\"bp-box--icon lazy\" data-src=\"\/wp-content\/uploads\/visualmap.svg\"><\/div>\n<h4 class=\"bp-box--title\">MAPA VISUAL<\/h4>\n<\/div>\n<div class=\"p-3 p-lg-4\">\n<p>O mapa visual exibir&aacute; as rotas mais ideais entre os locais de destino na rede, que podem incluir:<\/p>\n<ul>\n<li class=\"mb-1\"><strong>Rota principal:<\/strong> um caminho real.<\/li>\n<li class=\"mb-1\"><strong>Miscellaneous Path:<\/strong> Um caminho planejado para backup.<\/li>\n<li class=\"mb-1\"><strong>Solicitar rota:<\/strong> Rotas dispon&iacute;veis mediante solicita&ccedil;&atilde;o.<\/li>\n<\/ul><\/div>\n<\/div>\n<\/div>\n<div class=\"col-12\">\n<div class=\"bp-box rounded h-100\">\n<div class=\"bp-box--header rounded-top\">\n<h4 class=\"bp-box--title ps-0\">FUN&Ccedil;&Otilde;ES DE SUPORTE<\/h4>\n<\/div>\n<div class=\"p-3 p-lg-4\">\n<p>Op&ccedil;&otilde;es adicionais de filtro:<\/p>\n<ul>\n<li class=\"mb-1\"><strong>Prote&ccedil;&atilde;o de link:<\/strong> evita os cabos usados &#8203;&#8203;no caminho principal.<\/li>\n<li class=\"mb-1\"><strong>Prote&ccedil;&atilde;o de n&oacute;:<\/strong> impede o uso de POP na rota principal.<\/li>\n<li class=\"mb-1\"><strong>Apenas informa&ccedil;&otilde;es reais:<\/strong> apenas rotas reais na rede, sem rotas sob demanda.<\/li>\n<li class=\"mb-1\"><strong>Evite n&oacute;s nos EUA:<\/strong> rotas que n&atilde;o t&ecirc;m parada na regi&atilde;o dos EUA.<\/li>\n<\/ul><\/div>\n<\/div>\n<\/div>\n<\/div>\n<h2 class=\"fs-6 text-secondary mb-4\">BENEF&Iacute;CIOS DO APLICATIVO BEST PATH DE IPTP NETWORKS<\/h2>\n<div class=\"row g-3 justify-content-center mb-5\">\n<div class=\"col-12 col-md-4\">\n<div class=\"bp-box rounded p-3 h-100\">\n<h4 class=\"text-normal mt-2 fw-bold text-primary fs-6 text-center\">Mostre sua rede de cobertura<\/h4>\n<ul class=\"mb-0\">\n<li>Melhor visualiza&ccedil;&atilde;o de rotas e lat&ecirc;ncias.<\/li>\n<li>Apresenta uma imagem f&aacute;cil de entender de cada conectividade, incluindo rotas protegidas e disponibilidade de rota.<\/li>\n<\/ul><\/div>\n<\/div>\n<div class=\"col-12 col-md-4\">\n<div class=\"bp-box rounded p-3 h-100\">\n<h4 class=\"text-normal mt-2 fw-bold text-primary fs-6 text-center\">O material de marketing perfeito para impressionar seu p&uacute;blico<\/h4>\n<ul class=\"mb-0\">\n<li>Chega de redes complexas com uma experi&ecirc;ncia aprimorada para seus clientes e parceiros.<\/li>\n<li>Permita que seus clientes e parceiros projetem livremente suas rotas ideais.<\/li>\n<\/ul><\/div>\n<\/div>\n<div class=\"col-12 col-md-4\">\n<div class=\"bp-box rounded p-3 h-100\">\n<h4 class=\"text-normal mt-2 fw-bold text-primary fs-6 text-center\">Suporte 24\/7\/365<\/h4>\n<ul class=\"mb-0\">\n<li>Servi&ccedil;o de assist&ecirc;ncia t&eacute;cnica qualificado.<\/li>\n<li>Atualiza&ccedil;&otilde;es frequentes e corre&ccedil;&otilde;es de patches.<\/li>\n<\/ul><\/div>\n<\/div>\n<div class=\"col-12 col-md-4\">\n<div class=\"bp-box rounded p-3 h-100\">\n<h4 class=\"text-normal mt-2 fw-bold text-primary fs-6 text-center\">Conveni&ecirc;ncia de uso<\/h4>\n<ul class=\"mb-0\">\n<li>Totalmente intuitivo e f&aacute;cil de usar.<\/li>\n<li>Configure imediatamente seu pr&oacute;prio Best Path sem nenhum processo complicado.<\/li>\n<\/ul><\/div>\n<\/div>\n<div class=\"col-12 col-md-4\">\n<div class=\"bp-box rounded p-3 h-100\">\n<h4 class=\"text-normal mt-2 fw-bold text-primary fs-6 text-center\">Solu&ccedil;&atilde;o sob medida<\/h4>\n<ul class=\"mb-0\">\n<li>Adequado para ISPs de todos os n&iacute;veis e tamanhos.<\/li>\n<li>Personalize seu aplicativo Best Path ideal removendo ou adicionando mais recursos &agrave; medida que voc&ecirc; dimensiona.<\/li>\n<\/ul><\/div>\n<\/div>\n<div class=\"col-12 col-md-4\">\n<div class=\"bp-box rounded p-3 h-100\">\n<h4 class=\"text-normal mt-2 fw-bold text-primary fs-6 text-center\">Oportunidade de colabora&ccedil;&atilde;o<\/h4>\n<ul class=\"mb-0\">\n<li>A oportunidade de colaborar com outros parceiros da Best Path para interagir uns com os outros.<\/li>\n<li>Aumente sua presen&ccedil;a online e seu poder de marketing.<\/li>\n<\/ul><\/div>\n<\/div>\n<div class=\"col-12 col-md-4\">\n<div class=\"bp-box rounded p-3 h-100\">\n<h4 class=\"text-normal mt-2 fw-bold text-primary fs-6 text-center\">N&iacute;vel m&aacute;ximo de seguran&ccedil;a<\/h4>\n<ul class=\"mb-0\">\n<li>Sem an&uacute;ncios<\/li>\n<li>Nenhuma coleta de dados para terceiros<\/li>\n<li>Sem vazamento de informa&ccedil;&otilde;es<\/li>\n<li>O aplicativo Best Path far&aacute; integra&ccedil;&atilde;o com o banco de dados da sua empresa<\/li>\n<li>Voc&ecirc; ter&aacute; controle total sobre seus dados de rede<\/li>\n<\/ul><\/div>\n<\/div>\n<\/div>\n<p>   Clique no bot&atilde;o abaixo para preencher o formul&aacute;rio de solicita&ccedil;&atilde;o e construir seu aplicativo Best Path ideal.<\/p>\n<h2 class=\"fs-6 text-secondary mb-4\">FERRAMENTA BEST PATH PARA WEB<\/h2>\n<div class=\"text-center mb-5 py-5 rounded mx-auto\" style=\"background-image: url('\/wp-content\/uploads\/best-path-app-bg.png')\">\n   <a href=\"https:\/\/web.la.iptp.net\/pt_PT\/iptp-tools\/best-path\/\" class=\"btn btn-primary text-uppercase px-3 px-lg-5 text-white py-3 rounded\" target=\"_blank\" rel=\"noopenner noopener\">EXPERIMENTE NOSSA VERS&Atilde;O WEB<\/a>\n<\/div>\n<h2 class=\"fs-6 text-secondary mb-4\">VISUALIZE TODA A SUA REDE<\/h2>\n<p>Clique no bot&atilde;o abaixo para preencher o formul&aacute;rio de solicita&ccedil;&atilde;o e construir seu aplicativo Best Path ideal:<\/p>\n<div class=\"text-center my-5 p-4 rounded mx-auto\" style=\"background-color:#e9edf5;max-width:615px\">\n     <button class=\"js-target-div btn btn-secondary px-3 px-lg-5 text-white py-3 rounded\" target=\"_blank\" rel=\"noopenner\" data-target=\"jumboIX__modal_dev\">CRIE SEU APLICATIVO BEST PATH IDEAL<\/button>\n   <\/div>\n<div class=\"div-hidden-btn\">\t<div>\r\n\t\t<button type=\"button\" class=\"btn btn-primary btn__jumboix btn-lg js-target-div mt-2 js-fixed-button-open-request-form \" data-target=\"jumboIX__modal_dev\">\r\n\t\t\tRequest a quote\t\t<\/button>\r\n\t<\/div>\r\n\r\n\t<div id=\"jumboIX__modal_dev\" class=\"popup-jumboIX-modal-s1 wrap-jumboix wrap-jumboix__2 v-modal\">\r\n\t\t<div class=\"modal__inner\">\r\n\t\t\t<button class=\"x-close js-x-close\">x<\/button>\r\n\r\n\t\t\t<h2 class=\"jumbolix-heading \">\r\n\t\t\t\tA quote for Best Path tool development\t\t\t<\/h2>\r\n\r\n\t\t\t\r\n\r\n\r\n\t\t\t<form method=\"post\" class=\"js-form-ajax-request_form_bestpath_tool js_form_get_token css-form-mod-v2\">\r\n\t\t\t\t   <input type=\"hidden\" name=\"_wp_http_referer\" value=\"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/pages\/25218\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"_current_title\" value=\"IPTP Networks\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"security\" value=\"39862701f1\">\r\n   <input type=\"hidden\" name=\"form_time\" value=\"1778668971\">\r\n   <input type=\"text\" name=\"website\" style=\"display:none\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"js_check\" class=\"no-check\" value=\"\">\r\n   \r\n\r\n\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"service\" value=\"A Quote For Best Path Tool Development\">\r\n\t\t\t\t\r\n\r\n\t\t\t\t\r\n\r\n\r\n\r\n\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"your_name\" data-test class=\"form-control form-control--border-bottom\" placeholder=\"Your name *\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"email\" class=\"form-control form-control--border-bottom\" placeholder=\"E-mail *\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"organisation\" class=\"form-control form-control--border-bottom\" placeholder=\"Organisation *\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<div class=\"wrap-intl-tel-input\">\r\n\t\t\t\t\t\t\t<input type=\"text\" name=\"asnumber\" class=\"form-control form-control--border-bottom intl-tel-input no-check\" placeholder=\"Phone\">\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 line-group\">\r\n\t\t\t\t\t\t<div class=\"w-100\">\r\n\t\t\t\t\t\t\t<label style=\"font-weight: bold\" for=\"ms\">Describe your request<\/label>\r\n\t\t\t\t\t\t\t<textarea name=\"message\" id=\"ms\" cols=\"30\" rows=\"6\" class=\"form-control form-control--border-bottom\" placeholder=\"Quick overview *\"><\/textarea>\r\n\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"col-12 col-md-6\">\r\n\t\t\t\t\t\t<div class=\"mt-4 fw-bold mb-3\">Release as<\/div>\r\n\t\t\t\t\t\t<div class=\"form-check mb-2\">\r\n\t\t\t\t\t\t\t<input class=\"form-check-input\" name=\"tool[]\" type=\"checkbox\" value=\"Wordpress Plugin\" id=\"WordpressPlugin\" checked>\r\n\t\t\t\t\t\t\t<label class=\"form-check-label\" for=\"WordpressPlugin\">Wordpress Plugin<\/label>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"form-check mb-2\">\r\n\t\t\t\t\t\t\t<input class=\"form-check-input\" name=\"tool[]\" type=\"checkbox\" value=\"PHP\" id=\"PHP\">\r\n\t\t\t\t\t\t\t<label class=\"form-check-label\" for=\"PHP\">PHP<\/label>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"form-check mb-2\">\r\n\t\t\t\t\t\t\t<input class=\"form-check-input\" name=\"tool[]\" type=\"checkbox\" value=\"Web-based Android App\" id=\"Web-basedAndroidApp\">\r\n\t\t\t\t\t\t\t<label class=\"form-check-label\" for=\"Web-basedAndroidApp\">Web-based Android App<\/label>\r\n\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<!-- <select name=\"tool\" class=\"form-select w-auto text-primary mb-3 rounded text-uppercase fw-bold\" aria-label=\"Choose location\" required>\r\n\t\t\t\t\t\t<option value=\"\" hidden>CHOOSE<\/option>\r\n\t\t\t\t\t\t<option value=\"Wordpress Plugin\">Wordpress Plugin<\/option>\r\n\t\t\t\t\t\t<option value=\"PHP\">PHP<\/option>\r\n\t\t\t\t\t\t<option value=\"Web-based Android App\">Web-based Android App<\/option>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t<\/select> -->\r\n\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 line-group\">\r\n\t\t\t\t\t\t* required fields\t\t\t\t\t<\/div>\r\n\r\n\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 text-center\">\r\n\t\t\t\t\t\t<!-- <div class=\"line-group captcha_md mt-4\">\r\n\t\t\t\t\t\t\t<div id=\"captcha2\" class=\"captcha__label\"><\/div>\r\n\t\t\t\t\t\t\t<span class=\"fa fa-refresh catpcha_refresh2\"><\/span>\r\n\t\t\t\t\t\t\t<input id=\"cpatchaJumboIX\" type=\"text\" name=\"captcha\" class=\"line-group__input--213 captcha__input--custom\" placeholder=\"Captcha code\" \/>\r\n\t\t\t\t\t\t<\/div> -->\r\n\t\t\t\t\t\t<button class=\"btn btn__jumboix btn-secondary fs-5 w-100 py-3 rounded\">\r\n\t\t\t\t\t\t\t\tRequest development quotation\t\t\t\t\t\t\t<\/button>\r\n\t\t\t\t\t\t\r\n\r\n\r\n\r\n\t\t\t\t\t\t<div class=\"jumboIX_completed js-jumboIX_completed--success \">\r\n\t\t\t\t\t\t\tThank you for your request\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div class=\"jumboIX_completed jumboIX_completed--error\"><\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/form>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<div class=\"div-overlay\"><\/div>\r\n\r\n<\/div>\n<p>Se voc&ecirc; tiver alguma d&uacute;vida ou preocupa&ccedil;&atilde;o, sinta-se &agrave; vontade para entrar em contato com nossa equipe em <a><span class=\"sp-user\">sales<\/span><span class=\"sp-domain\">iptp.net<\/span><\/a> ou use o bot&atilde;o azul &laquo;<a href=\"javascript:popupchat()\">Live Assistant<\/a>&raquo; no canto inferior direito da p&aacute;gina.<\/p>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/pages\/25218"}],"collection":[{"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/comments?post=25218"}],"version-history":[{"count":61,"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/pages\/25218\/revisions"}],"predecessor-version":[{"id":39993,"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/pages\/25218\/revisions\/39993"}],"wp:attachment":[{"href":"https:\/\/web.la.iptp.net\/pt_PT\/wp-json\/wp\/v2\/media?parent=25218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}