{"id":27649,"date":"2023-09-05T21:35:36","date_gmt":"2023-09-05T18:35:36","guid":{"rendered":"https:\/\/web-dev.iptp.net\/?p=27649"},"modified":"2026-05-08T09:41:21","modified_gmt":"2026-05-08T06:41:21","slug":"lacnic-40-lacnog-2023","status":"publish","type":"post","link":"https:\/\/web.la.iptp.net\/es_ES\/lacnic-40-lacnog-2023\/","title":{"rendered":"Eventos LACNIC 40-LACNOG 2023"},"content":{"rendered":"<p><strong>Date: 2-6 October 2023<br>\nVenue: F&aacute;brica de Negocios, Fortaleza<br>\nPlace: Fortaleza, Brasil<br>\nWebsite: <a href=\"https:\/\/lacnic40.lacnic.net\" rel=\"noopener\" target=\"_blank\">https:\/\/lacnic40.lacnic.net<\/a><\/strong><\/p><p>IPTP Networks Participar&aacute; en LACNIC 40 &ndash; LACNOG 2023 en Fortaleza, Brasil<\/p><p>Art&iacute;culo: Nos complace anunciar que IPTP Networks estar&aacute; presente en el esperado evento LACNIC 40 &ndash; LACNOG 2023. Este evento de cinco d&iacute;as, dedicado a fomentar la colaboraci&oacute;n en la comunidad de Internet, se llevar&aacute; a cabo del 2 al 6 de octubre en Fortaleza, Brasil.<\/p><p>LACNIC 40 &ndash; LACNOG 2023 re&uacute;ne a expertos, profesionales y entusiastas de diversos sectores, como tecnolog&iacute;a de la informaci&oacute;n, educaci&oacute;n, sociedad civil y gobierno, entre otros. El evento ofrece oportunidades valiosas para capacitaci&oacute;n de alto nivel, intercambio de conocimientos y networking con m&aacute;s de 800 participantes.<\/p><p>Nos vemos en la F&aacute;brica de Negocios en Fortaleza, Brasil, para el LACNIC 40 &ndash; LACNOG 2023 que contar&aacute; con tutoriales t&eacute;cnicos, presentaciones de expertos, el Foro P&uacute;blico de Pol&iacute;ticas y m&aacute;s. <\/p><p>Estamos ansiosos por participar en estas discusiones, aprender de nuestros colegas y contribuir al avance del panorama de Internet.<\/p><p>Mant&eacute;nte atento a las actualizaciones del evento y nuestras experiencias mientras nos unimos a este vibrante encuentro de actores de Internet.<\/p><p>Para agendar una reuni&oacute;n con nosotros, env&iacute;anos un mensaje a <span class=\"sp-user\">marketing<\/span><span class=\"sp-domain\">iptp.net<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Date: 2-6 October 2023<br \/>\nVenue: F\u00e1brica de Negocios, Fortaleza<br \/>\nPlace: Fortaleza, Brasil<br \/>\nWebsite: https:\/\/lacnic40.lacnic.net<\/p>\n","protected":false},"author":4,"featured_media":27650,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"template-event-detail.php","format":"standard","meta":[],"categories":[22],"tags":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/posts\/27649"}],"collection":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/comments?post=27649"}],"version-history":[{"count":28,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/posts\/27649\/revisions"}],"predecessor-version":[{"id":42394,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/posts\/27649\/revisions\/42394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/media\/27650"}],"wp:attachment":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/media?parent=27649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/categories?post=27649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/tags?post=27649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}