{"id":73,"date":"2019-12-10T11:53:07","date_gmt":"2019-12-10T08:53:07","guid":{"rendered":"https:\/\/web-mng.iptp.com\/?page_id=73"},"modified":"2023-11-29T23:45:12","modified_gmt":"2023-11-29T20:45:12","slug":"company","status":"publish","type":"page","link":"https:\/\/web.la.iptp.net\/es_ES\/company\/","title":{"rendered":"La Empresa"},"content":{"rendered":"<p>Nuestro objetivo es ayudar a las empresas a resolver todos sus desaf&iacute;os en este mundo de TI que cambia r&aacute;pidamente. Siendo nuestra principal prioridad estar disponibles en el momento adecuado, en el lugar correcto y con las soluciones id&oacute;neas, que se adaptan de manera &oacute;ptima seg&uacute;n los requisitos individuales &uacute;nicos. Nos enorgullece llamar amigos a nuestros socios y clientes, y nos alegra de sobremanera que nuestra asociaci&oacute;n les brinde gran satisfacci&oacute;n.<\/p><p>Desde sus inicios en 1996, el equipo IPTP ha ayudado mundialmente a alrededor de [clients] clientes corporativos, a trav&eacute;s de su viaje a la transformaci&oacute;n digital, racionalizando sus negocios, reduciendo costos, expandiendo y asegurando su infraestructura y adelant&aacute;ndose a la competencia. Desde su fundaci&oacute;n, la compa&ntilde;&iacute;a continu&oacute; con consistencia, trabajo duro e innovaci&oacute;n. Ahora hemos crecido hasta convertirnos en un <a href=\"https:\/\/web.la.iptp.net\/es_ES\/company\/iptp-networks-in-numbers\/\">importante grupo internacional y una organizaci&oacute;n de clase mundial<\/a>. Operamos un backbone global como un Internet Service Provider (ISP) de red Tier-1 que provee conectividad a trav&eacute;s de m&aacute;s de 228 centros de datos ON-NET a nivel mundial.<\/p><p>En esta &aacute;rea encontrar&aacute;s las siguientes p&aacute;ginas: <\/p><li><a href=\"https:\/\/web.la.iptp.net\/es_ES\/company\/iptp-networks-in-numbers\/\">Nuestros Logros en N&uacute;meros<\/a><\/li><li><a href=\"https:\/\/web.la.iptp.net\/es_ES\/company\/meet-our-team\/\">Conoce a Nuestro Equipo<\/a><\/li><li><a href=\"https:\/\/web.la.iptp.net\/es_ES\/careers\/\">Carreras<\/a><\/li><li><a href=\"https:\/\/web.la.iptp.net\/es_ES\/company\/contacts\/\">Contactos<\/a><\/li>\n","protected":false},"excerpt":{"rendered":"<p>\n Information will be added soon <\/p>\n<p> &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/73"}],"collection":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/comments?post=73"}],"version-history":[{"count":225,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/73\/revisions"}],"predecessor-version":[{"id":28675,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/73\/revisions\/28675"}],"wp:attachment":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/media?parent=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}