{"id":261,"date":"2016-09-20T18:12:39","date_gmt":"2016-09-20T15:12:39","guid":{"rendered":"https:\/\/web-mng.iptp.com\/?page_id=261"},"modified":"2026-04-21T11:37:23","modified_gmt":"2026-04-21T08:37:23","slug":"about-us","status":"publish","type":"page","link":"https:\/\/web.la.iptp.net\/es_ES\/about-us\/","title":{"rendered":"Sobre Nosotros"},"content":{"rendered":"<section>\n<h2 class=\"text-normal text-secondary\">RESUMEN<\/h2>\n<div class=\"position-relative mb-4 css-inline-all\">IPTP Networks es un integrador de sistemas l&iacute;der, red de un solo lugar de nivel 1 \n<div class=\"as__hover\" data-as-hover=\"504\"><a href=\"javascript:void(0);\">(AS 3356)<\/a><\/div>\n<p>, proveedor de servicios de Internet <\/p>\n<div class=\"as__hover\" data-as-hover=\"1046\">(<a href=\"javascript:void(0);\">AS 41095<\/a><\/div>\n<p>, <\/p>\n<div class=\"as__hover\" data-as-hover=\"23872\"><a href=\"javascript:void(0);\">AS 263681<\/a><\/div>\n<p>, <\/p>\n<div class=\"as__hover\" data-as-hover=\"23871\"><a href=\"javascript:void(0);\">AS 51601<\/a><\/div>\n<p>, <\/p>\n<div class=\"as__hover\" data-as-hover=\"24041\"><a href=\"javascript:void(0);\">AS 140951<\/a><\/div>\n<p>, <\/p>\n<div class=\"as__hover\" data-as-hover=\"23869\"><a href=\"javascript:void(0);\">AS 135993<\/a>)<\/div>\n<p> y grupo de empresas de desarrollo de software que opera en todo el mundo con oficinas en Limassol (Chipre), &Aacute;msterdam (Pa&iacute;ses Bajos), Nueva York (EE. UU.), Hong Kong (RAE de China), Lima (Per&uacute;), S&atilde;o Paulo (Brasil), La Paz (Bolivia) y Ciudad Ho Chi Minh (Vietnam).<\/p><\/div>\n<p class=\"mb-4\">Originalmente fundada en Chipre (1996) como integrador de sistemas, despu&eacute;s de [year] a&ntilde;os de desarrollo exitoso, la empresa IPTP Networks (2004) creci&oacute; hasta convertirse en un importante grupo internacional y una organizaci&oacute;n de clase mundial. Operamos una red troncal global como proveedor de servicios de Internet (ISP) de red de nivel 1 que proporciona conectividad a trav&eacute;s de 228 puntos de presencia en todo el mundo.<\/p>\n<h3 class=\"text-normal text-primary\">CRONOLOG&Iacute;A\/ HISTORIA<\/h3>\n<div class=\"row row-cols-1 row-cols-sm-2 row-cols-lg-3 gx-2 gy-3 mb-5\">\n<div class=\"col\">\n<div class=\"have-shadow lift rounded h-100 p-3\">\n            <strong class=\"text-secondary\">1996<\/strong>: Se funda IPTP Networks como integrador de sistemas en Chipre, comenzando su viaje como entidad pionera en el campo.\n         <\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"have-shadow lift rounded h-100 p-3\">\n            <strong class=\"text-secondary\">2004<\/strong>: IPTP Networks ha crecido hasta convertirse en un importante conglomerado mundial y una corporaci&oacute;n sin igual, mostrando un nivel excepcional de experiencia.\n         <\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"have-shadow lift rounded h-100 p-3\">\n            <strong class=\"text-secondary\">2006<\/strong>: IPTP Networks expande su presencia global al abrir una oficina en la ic&oacute;nica ciudad de &Aacute;msterdam, en los Pa&iacute;ses Bajos.\n         <\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"have-shadow lift rounded h-100 p-3\">\n            <strong class=\"text-secondary\">2009<\/strong>: IPTP Networks extiende su alcance al otro lado del Atl&aacute;ntico, inaugurando una oficina en los Estados Unidos de Am&eacute;rica, un hito significativo para la compa&ntilde;&iacute;a.\n         <\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"have-shadow lift rounded h-100 p-3\">\n            <strong class=\"text-secondary\">2010<\/strong>: IPTP Networks refuerza su presencia en la regi&oacute;n de Asia y el Pac&iacute;fico, inaugurando una oficina de &uacute;ltima generaci&oacute;n en la bulliciosa metr&oacute;polis de Hong Kong.\n         <\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"have-shadow lift rounded h-100 p-3\">\n            <strong class=\"text-secondary\">2017<\/strong>: IPTP Networks contin&uacute;a su impulso de expansi&oacute;n, estableci&eacute;ndose en la pr&oacute;spera ciudad de Vietnam, Ho Chi Minh, y tambi&eacute;n establece su presencia en la capital de Per&uacute;, Lima.\n         <\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"have-shadow lift rounded h-100 p-3\">\n            <strong class=\"text-secondary\">2020<\/strong>: IPTP Networks emprende un nuevo viaje, inaugurando una oficina en el coraz&oacute;n de Bolivia, La Paz, como parte de su compromiso de expandir su presencia global.\n         <\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"have-shadow lift rounded h-100 p-3\">\n            <strong class=\"text-secondary\">2021<\/strong>: IPTP Networks expande sus operaciones en Vietnam, estableciendo una oficina en Danang, mejorando as&iacute; a&uacute;n m&aacute;s sus capacidades de conectividad en la regi&oacute;n.\n         <\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"have-shadow lift rounded h-100 p-3\">\n            <strong class=\"text-secondary\">2022<\/strong>: IPTP Networks obtiene la licencia de ISP esencial para brindar servicios de telecomunicaciones en Vietnam, consolidando su posici&oacute;n como proveedor l&iacute;der de soluciones de conectividad de vanguardia.\n         <\/div>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-12 col-lg-4\">\n<h4 class=\"fs-56 text-primary\">MISI&Oacute;N<\/h4>\n<p>Llevar a cabo los proyectos de nuestros clientes y nuevas capacidades en el mundo de las telecomunicaciones. Para lograr esto, nos enfocamos en brindar soporte completo a nuestros clientes e implementar proyectos &uacute;nicos, diversos y t&eacute;cnicamente interesantes.<\/p>\n<h4 class=\"fs-56 text-primary\">VISI&Oacute;N<\/h4>\n<p>Ser el integrador preeminente mundial de sistemas de conectividad, que atiende de manera confiable nichos de mercado de todo tipo y lugar.<\/p>\n<h4 class=\"fs-56 text-primary\">ESLOGAN<\/h4>\n<p>&iexcl;No solo una red m&aacute;s grande sino la mejor!<\/p>\n<\/div>\n<div class=\"col-12 col-lg-8\">\n<div class=\"bg-secondary rounded p-2\">\n<h4 class=\"fs-56 text-white my-2\">VALORES FUNDAMENTALES<\/h4>\n<div class=\"bg-white p-3 rounded\">\n               1) <strong>Estar un paso adelante<\/strong>: Nos esforzamos por ser l&iacute;deres en los mercados globales. Estamos siempre un paso adelane en tecnolog&iacute;a, conocimientos y cualidades de nuestros empleados. Anticipamos lo que suceder&aacute; ma&ntilde;ana y estamos preparados para ello hoy. Estamos en constante desarrollo y aprendizaje. Cada d&iacute;a tratamos de trabajar mejor que ayer.<br>\n               2) <strong>Independencia<\/strong>: IPTP se mantiene firmemente independiente y dedicada a atender de manera &oacute;ptima las necesidades de nuestros clientes, sin los impedimentos y las pol&iacute;ticas de una empresa endeudda con partes externas m&aacute;s grandes (una empresa matriz, mercados financieros o afiliaci&oacute;n). Esto nos permite ser libres para innovar y adaptarnos.<br>\n               3) <strong>Eficacia<\/strong>: Siempre encontramos las mejores soluciones a los problemas. Somos eficientes en todo lo que hacemos: al cumplir con nuestros objetivos, utilizamos los recursos de la empresa de la manera m&aacute;s eficiente posible y mejoramos constantemente nuestros procesos de trabajo. No hay obst&aacute;culos que nos impidan encontrar las soluciones m&aacute;s eficaces.<br>\n               4) <strong>Equipo Unificado<\/strong>: todos somos IPTP. Tenemos objetivos comunes. Trabajamos en equipos estables y transitorios, a trav&eacute;s de continentes y especializaciones, lo que incorpora perspectivas amplias y pomueve el desarrollo profesional. Trabajar en equipos de personas con ideas afines ayuda a lograr resultados &uacute;nicos. El &eacute;xito de los empleados es el &eacute;xito de la empresa.<br>\n               5) <strong>Respeto<\/strong>: Respetamos a nuestros colegas, clientes, socios y proveedores. Siempre escuchamos atentamente y nos escuchamos unos a otros independientemente de nuestras posiciones y lugar de trabajo. Respetamos la historia y las tradiciones de la industria. Los logros del pasado nos inspiran a obtener nuevas victorias.\n            <\/div>\n<\/div>\n<\/div>\n<\/div>\n<h3 class=\"text-primary\">SERVICIOS<\/h3>\n<div class=\"row row-cols-sm-2 row-cols-lg-3 gx-2 gy-3 mb-5 row-test masonry\">\n<div class=\"col col-masonry\">\n<div class=\"have-shadow lift rounded p-3\">\n<h4 class=\"fs-56 fw-bold text-secondary\">SOLUCIONES IPTP<\/h4>\n<ul>\n<li class=\"mb-0\">Servicio de Hosting Gestionado<\/li>\n<li class=\"mb-0\">Almacenamiento Distribuido Gestionado<\/li>\n<li class=\"mb-0\">LAN Inal&aacute;mbrica Administrada<\/li>\n<li class=\"mb-0\">Aceleraci&oacute;n de WAN<\/li>\n<li class=\"mb-0\">Mitigaci&oacute;n de DDoS (DMMS)<\/li>\n<li class=\"mb-0\">Control de Acceso<\/li>\n<li class=\"mb-0\">Videovigilancia<\/li>\n<li class=\"mb-0\">Comunicaci&oacute;n M&oacute;vil Gestionada<\/li>\n<li class=\"mb-0\">Comunicaciones Unificadas de Cisco<\/li>\n<li class=\"mb-0\">Telepresencia de Cisco<\/li>\n<li class=\"mb-0\">Seguimiento Mundial<\/li>\n<li class=\"mb-0\">SmartSpaces (automatizaci&oacute;n de edificios)<\/li>\n<li class=\"mb-0\">Internet de las Cosas (IoT)<\/li>\n<li class=\"mb-0\">XRM (ERP y CRM)<\/li>\n<\/ul><\/div>\n<\/div>\n<div class=\"col col-masonry\">\n<div class=\"have-shadow lift rounded p-3\">\n<h4 class=\"fs-56 fw-bold text-secondary\">HARDWARE<\/h4>\n<ul>\n<li class=\"mb-0\">In-house development<\/li>\n<li class=\"mb-0\">Cisco<\/li>\n<li class=\"mb-0\">EMC2\/RSA<\/li>\n<li class=\"mb-0\">Schneider Electric\/APC<\/li>\n<li class=\"mb-0\">Hewlett-Packard<\/li>\n<li class=\"mb-0\">Seagate<\/li>\n<li class=\"mb-0\">Supermicro<\/li>\n<li class=\"mb-0\">Kingston<\/li>\n<\/ul><\/div>\n<\/div>\n<div class=\"col col-masonry\">\n<div class=\"have-shadow lift rounded p-3\">\n<h4 class=\"fs-56 fw-bold text-secondary\">XAAS (CUALQUIER COSA COMO SERVICIO)<\/h4>\n<ul>\n<li class=\"mb-0\">IaaS (Infraestructura como servicio)<\/li>\n<li class=\"mb-0\">NaaS (Red como servicio)<\/li>\n<li class=\"mb-0\">PaaS (Plataforma como servicio)<\/li>\n<li class=\"mb-0\">SaaS (Software como servicio)<\/li>\n<li class=\"mb-0\">MSaaS (Software gestionado como servicio)<\/li>\n<li class=\"mb-0\">SECaaS (Seguridad como servicio)<\/li>\n<li class=\"mb-0\">DaaS (Escritorio como servicio)<\/li>\n<li class=\"mb-0\">MVaaS (Video administrado como servicio)<\/li>\n<li class=\"mb-0\">MBaaS (Backend m&oacute;vil como servicio)<\/li>\n<li class=\"mb-0\">MaaS (Metal como servicio)<\/li>\n<\/ul><\/div>\n<\/div>\n<div class=\"col col-masonry\">\n<div class=\"have-shadow lift rounded p-3\">\n<h4 class=\"fs-56 fw-bold text-secondary\">INFRAESTRUCTURA<\/h4>\n<ul>\n<li class=\"mb-0\">Centros de Datos (3 propios y 228 alquilados)<\/li>\n<li class=\"mb-0\">Fibras Oscuras<\/li>\n<li class=\"mb-0\">Enlaces Satelitales<\/li>\n<li class=\"mb-0\">Enlaces Radio Terrestres<\/li>\n<li class=\"mb-0\">Capacidades IRU Submarinas<\/li>\n<li class=\"mb-0\">Canalizaci&oacute;n<\/li>\n<\/ul><\/div>\n<\/div>\n<div class=\"col col-masonry\">\n<div class=\"have-shadow lift rounded p-3\">\n<h4 class=\"fs-56 fw-bold text-secondary\">SERVICIOS TELCO<\/h4>\n<ul>\n<li class=\"mb-0\">IP Transit<\/li>\n<li class=\"mb-0\">IX Transit<\/li>\n<li class=\"mb-0\">MPLS<\/li>\n<li class=\"mb-0\">IPLC<\/li>\n<li class=\"mb-0\">EPL Ethernet<\/li>\n<li class=\"mb-0\">Hosting Dedicado<\/li>\n<li class=\"mb-0\">Nube Privada<\/li>\n<li class=\"mb-0\">CDN Privado<\/li>\n<li class=\"mb-0\">IaaS<\/li>\n<li class=\"mb-0\">NaaS<\/li>\n<\/ul><\/div>\n<\/div>\n<div class=\"col col-masonry\">\n<div class=\"have-shadow lift rounded p-3\">\n<h4 class=\"fs-56 fw-bold text-secondary\">SOFTWARE<\/h4>\n<ul>\n<li class=\"mb-0\">Desarrollo Interno<\/li>\n<li class=\"mb-0\">Cisco<\/li>\n<li class=\"mb-0\">Microsoft<\/li>\n<li class=\"mb-0\">VMware<\/li>\n<li class=\"mb-0\">RedHat<\/li>\n<li class=\"mb-0\">Citrix<\/li>\n<\/ul><\/div>\n<\/div>\n<\/div>\n<h3 class=\"text-primary\">LOGROS<\/h3>\n<div class=\"wrap-net-number mb-3rem\">\n<div class=\"swiper-container net-number net-number-swiper\">\n<div class=\"swiper-wrapper\">\n<div class=\"swiper-slide\">\n<div class=\"net-number__item\">\n<div class=\"--title\">228<\/div>\n<div>\n                     <img decoding=\"async\" class=\"--icon lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"pop\" data-src=\"\/wp-content\/uploads\/pop.svg\">\n                  <\/div>\n<div class=\"--content\">Puntos de presencia<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"net-number__item\">\n<div class=\"--title\">[cablesys]+<\/div>\n<div>\n                     <img decoding=\"async\" class=\"--icon lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"cable\" data-src=\"\/wp-content\/uploads\/cable.svg\">\n                  <\/div>\n<div class=\"--content\">Sistemas de cable terrestre y submarino<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"net-number__item\">\n<div class=\"--title\">[clients]<\/div>\n<div>\n                     <img decoding=\"async\" class=\"--icon lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"clients\" data-src=\"\/wp-content\/uploads\/clients.svg\">\n                  <\/div>\n<div class=\"--content\">Clientes y socios<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"net-number__item\">\n<div class=\"--title\">64<\/div>\n<div>\n                     <img decoding=\"async\" class=\"--icon lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"cities\" data-src=\"\/wp-content\/uploads\/cities.svg\">\n                  <\/div>\n<div class=\"--content\">Ciudades<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"net-number__item\">\n<div class=\"--title\">[leadings]+<\/div>\n<div>\n                     <img decoding=\"async\" class=\"--icon lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"experts\" data-src=\"\/wp-content\/uploads\/experts.svg\">\n                  <\/div>\n<div class=\"--content\">Expertos l&iacute;deres en todo el mundo<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"net-number__item\">\n<div class=\"--title\">37<\/div>\n<div>\n                     <img decoding=\"async\" class=\"--icon lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"countries\" data-src=\"\/wp-content\/uploads\/countries.svg\">\n                  <\/div>\n<div class=\"--content\">Pa&iacute;ses<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"net-number__item\">\n<div class=\"--title\">10<\/div>\n<div>\n                     <img decoding=\"async\" class=\"--icon lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"languages\" data-src=\"\/wp-content\/uploads\/languages.svg\">\n                  <\/div>\n<div class=\"--content\">Idiomas de soporte<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"net-number__item\">\n<div class=\"--title\">52<\/div>\n<div>\n                     <img decoding=\"async\" class=\"--icon lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"ixs\" data-src=\"\/wp-content\/uploads\/ixs.svg\">\n                  <\/div>\n<div class=\"--content\">Intercambios de Internet<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"net-number__item\">\n<div class=\"--title\">35++<\/div>\n<div>\n                     <img decoding=\"async\" class=\"--icon lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"capacity\" data-src=\"\/wp-content\/uploads\/capacity.svg\">\n                  <\/div>\n<div class=\"--content\">Tbit\/s de Capacidad de red total<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"net-number__item\">\n<div class=\"--title\">72<\/div>\n<div>\n                     <img decoding=\"async\" class=\"--icon lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"hosting\" data-src=\"\/wp-content\/uploads\/hosting.svg\">\n                  <\/div>\n<div class=\"--content\">Centros de datos para hosting\/colo<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"net-number__item\">\n<div class=\"--title\">[portspeering]<\/div>\n<div>\n                     <img decoding=\"async\" class=\"--icon lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"ports\" data-src=\"\/wp-content\/uploads\/ports.svg\">\n                  <\/div>\n<div class=\"--content\">Puertos con socios peering<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>      <!-- Add Arrows --><\/p>\n<div class=\"swiper-button-next net-number-next\"><\/div>\n<div class=\"swiper-button-prev net-number-prev\"><\/div>\n<\/div>\n<h3 class=\"text-primary\">JUNTA DIRECTIVA<\/h3>\n<div class=\"row g-4\">\n<div class=\"col-12 col-md-6\">\n<div class=\"have-shadow lift box-team rounded h-100\">\n<div class=\"box-team-header\">\n<h4 class=\"mb-0 fs-3 text-white\">Vladimir <br>Kangin<\/h4>\n<div><img decoding=\"async\" class=\"box-team-img lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"OXANAS\" data-src=\"\/wp-content\/uploads\/vk-photo.png\"><\/div>\n<\/div>\n<div class=\"box-team-content\">\n<div class=\"text-secondary fs-56 mb-3\">Fundador, CEO y<br>\n                  Director<\/div>\n<div class=\"mt-auto\">Hong Kong<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"col-12 col-md-6\">\n<div class=\"have-shadow lift box-team rounded h-100\">\n<div class=\"box-team-header\">\n<h4 class=\"mb-0 fs-3 text-white\">Oxana<br>Shvydkaya<\/h4>\n<div><img decoding=\"async\" class=\"box-team-img lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"OXANAS\" data-src=\"\/wp-content\/uploads\/OXANAS.jpg\"><\/div>\n<\/div>\n<div class=\"box-team-content\">\n<div class=\"text-secondary fs-56 mb-3\">Directora<br>\n                  Financiera<\/div>\n<div class=\"mt-auto\">Hong Kong<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"col-12 col-md-6\">\n<div class=\"have-shadow lift box-team rounded h-100\">\n<div class=\"box-team-header\">\n<h4 class=\"mb-0 fs-3 text-white\">Victor<br>Ma<\/h4>\n<div><img decoding=\"async\" class=\"box-team-img lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"VICTORM\" data-src=\"\/wp-content\/uploads\/VICTORM.jpg\"><\/div>\n<\/div>\n<div class=\"box-team-content\">\n<div class=\"text-secondary fs-56 mb-3\">L&iacute;der de Operaciones<br>\n                  Regionales<\/div>\n<div class=\"mt-auto\">Hong Kong<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"col-12 col-md-6\">\n<div class=\"have-shadow lift box-team rounded h-100\">\n<div class=\"box-team-header\">\n<h4 class=\"mb-0 fs-3 text-white\">Kim<br>Luu<\/h4>\n<div><img decoding=\"async\" class=\"box-team-img lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"KIML\" data-src=\"\/wp-content\/uploads\/KIML.jpg\"><\/div>\n<\/div>\n<div class=\"box-team-content\">\n<div class=\"text-secondary fs-56 mb-3\">BDM y<br>\n                  Directora General<\/div>\n<div class=\"mt-auto\">Vietnam<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"col-12 col-md-6\">\n<div class=\"have-shadow lift box-team rounded h-100\">\n<div class=\"box-team-header\">\n<h4 class=\"mb-0 fs-3 text-white\">Sergey<br>Kozhedoub<\/h4>\n<div><img decoding=\"async\" class=\"box-team-img lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"SERGEYK\" data-src=\"\/wp-content\/uploads\/SERGEYK.jpg\"><\/div>\n<\/div>\n<div class=\"box-team-content\">\n<div class=\"text-secondary fs-56 mb-3\">Director T&eacute;cnico<br>\n                  Global y de Arquitectura<br>\n                  de Red<\/div>\n<div class=\"mt-auto\">Pa&iacute;ses Bajos<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"col-12 col-md-6\">\n<div class=\"have-shadow lift box-team rounded h-100\">\n<div class=\"box-team-header\">\n<h4 class=\"mb-0 fs-3 text-white\">Ivan<br>Soldatov<\/h4>\n<div><img decoding=\"async\" class=\"box-team-img lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"IVANS\" data-src=\"\/wp-content\/uploads\/IVANS.jpg\"><\/div>\n<\/div>\n<div class=\"box-team-content\">\n<div class=\"text-secondary fs-56 mb-3\">Gerente de Desarrollo<br>\n                  de Negocios<\/div>\n<div class=\"mt-auto\">Hong Kong<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"col-12 col-md-6\">\n<div class=\"have-shadow lift box-team rounded h-100\">\n<div class=\"box-team-header\">\n<h4 class=\"mb-0 fs-3 text-white\">Vladimir<br>Sporykhin<\/h4>\n<div><img decoding=\"async\" class=\"box-team-img lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"Vladimir Sporykhin\" data-src=\"\/wp-content\/uploads\/VLADIMIRS.jpg\"><\/div>\n<\/div>\n<div class=\"box-team-content\">\n<div class=\"text-secondary fs-56 mb-3\">BDM<\/div>\n<div class=\"mt-auto\">Cyprus<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h3 class=\"text-secondary mt-5\">S&Iacute;GUENOS:<\/h3>\n<div class=\"row mb-5 g-3\">\n<div class=\"col-auto\">\n<div class=\"lift have-shadow rounded p-3\"><a href=\"https:\/\/www.facebook.com\/iptpnetworks\" target=\"_blank\" rel=\"noopener\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\" class=\"me-2\" fill=\"#06c\" width=\"25\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>Facebook<\/a><\/div>\n<\/div>\n<div class=\"col-auto\">\n<div class=\"lift have-shadow rounded p-3\"><a href=\"https:\/\/www.linkedin.com\/company\/iptpnetworks\" target=\"_blank\" rel=\"noopener\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\" class=\"me-2\" fill=\"#06c\" width=\"25\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg>Linkedin<\/a><\/div>\n<\/div>\n<div class=\"col-auto\">\n<div class=\"lift have-shadow rounded p-3\"><a href=\"https:\/\/t.me\/iptpnetworks\" target=\"_blank\" rel=\"noopener\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\" class=\"me-2\" fill=\"#06c\" width=\"25\"><path d=\"M248,8C111.033,8,0,119.033,0,256S111.033,504,248,504,496,392.967,496,256,384.967,8,248,8ZM362.952,176.66c-3.732,39.215-19.881,134.378-28.1,178.3-3.476,18.584-10.322,24.816-16.948,25.425-14.4,1.326-25.338-9.517-39.287-18.661-21.827-14.308-34.158-23.215-55.346-37.177-24.485-16.135-8.612-25,5.342-39.5,3.652-3.793,67.107-61.51,68.335-66.746.153-.655.3-3.1-1.154-4.384s-3.59-.849-5.135-.5q-3.283.746-104.608,69.142-14.845,10.194-26.894,9.934c-8.855-.191-25.888-5.006-38.551-9.123-15.531-5.048-27.875-7.717-26.8-16.291q.84-6.7,18.45-13.7,108.446-47.248,144.628-62.3c68.872-28.647,83.183-33.623,92.511-33.789,2.052-.034,6.639.474,9.61,2.885a10.452,10.452,0,0,1,3.53,6.716A43.765,43.765,0,0,1,362.952,176.66Z\"><\/path><\/svg>Telegram<\/a><\/div>\n<\/div>\n<div class=\"col-auto\">\n<div class=\"lift have-shadow rounded p-3\"><a href=\"https:\/\/twitter.com\/iptpnetworks\" target=\"_blank\" rel=\"noopener\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\" class=\"me-2\" fill=\"#06c\" width=\"25\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>Twitter<\/a><\/div>\n<\/div>\n<div class=\"col-auto\">\n<div class=\"lift have-shadow rounded p-3\"><a href=\"http:\/\/weixin.qq.com\/r\/JxOkvPnEjaTyrb3f90Y1\" target=\"_blank\" rel=\"noopener\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\" class=\"me-2\" fill=\"#06c\" width=\"25\"><path d=\"M385.2 167.6c6.4 0 12.6.3 18.8 1.1C387.4 90.3 303.3 32 207.7 32 100.5 32 13 104.8 13 197.4c0 53.4 29.3 97.5 77.9 131.6l-19.3 58.6 68-34.1c24.4 4.8 43.8 9.7 68.2 9.7 6.2 0 12.1-.3 18.3-.8-4-12.9-6.2-26.6-6.2-40.8-.1-84.9 72.9-154 165.3-154zm-104.5-52.9c14.5 0 24.2 9.7 24.2 24.4 0 14.5-9.7 24.2-24.2 24.2-14.8 0-29.3-9.7-29.3-24.2.1-14.7 14.6-24.4 29.3-24.4zm-136.4 48.6c-14.5 0-29.3-9.7-29.3-24.2 0-14.8 14.8-24.4 29.3-24.4 14.8 0 24.4 9.7 24.4 24.4 0 14.6-9.6 24.2-24.4 24.2zM563 319.4c0-77.9-77.9-141.3-165.4-141.3-92.7 0-165.4 63.4-165.4 141.3S305 460.7 397.6 460.7c19.3 0 38.9-5.1 58.6-9.9l53.4 29.3-14.8-48.6C534 402.1 563 363.2 563 319.4zm-219.1-24.5c-9.7 0-19.3-9.7-19.3-19.6 0-9.7 9.7-19.3 19.3-19.3 14.8 0 24.4 9.7 24.4 19.3 0 10-9.7 19.6-24.4 19.6zm107.1 0c-9.7 0-19.3-9.7-19.3-19.6 0-9.7 9.7-19.3 19.3-19.3 14.5 0 24.4 9.7 24.4 19.3.1 10-9.9 19.6-24.4 19.6z\"><\/path><\/svg>WeChat<\/a><\/div>\n<\/div>\n<\/div>\n<p>  <script>jQuery(document).ready(function(){new Masonry(\".masonry\",{})})<\/script><br>\n<\/p><\/section>\n","protected":false},"excerpt":{"rendered":"\n<p> \t 10 idiomas de soporte<br \/>\n \t 57 ciudades<br \/>\n \t 36 pa\u00edses<br \/>\n \t 36 sistemas de cables submarinos y terrestres<br \/>\n \t 452 intercambios de internet<br \/>\n \t 67 centros de alojamiento datos<\/li... \n\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/261"}],"collection":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/comments?post=261"}],"version-history":[{"count":479,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/261\/revisions"}],"predecessor-version":[{"id":42227,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/261\/revisions\/42227"}],"wp:attachment":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/media?parent=261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}