{"id":22055,"date":"2020-02-21T13:55:25","date_gmt":"2020-02-21T10:55:25","guid":{"rendered":"https:\/\/web-dev.iptp.net\/?page_id=22055"},"modified":"2026-04-20T11:17:18","modified_gmt":"2026-04-20T08:17:18","slug":"ixp-compare","status":"publish","type":"page","link":"https:\/\/web.la.iptp.net\/es_ES\/iptp-tools\/ixp-compare\/","title":{"rendered":"Comparativa de IXP"},"content":{"rendered":"<div class=\"row mt-5 gy-4\">\n<div class=\"col-auto col-md-6\">\n<div class=\"box-adv1 bg-primary rounded-lg p-2\">\n<h4 class=\"fw-normal mb-3 text-white\">IX Remoto<\/h4>\n<div class=\"bg-white rounded-lg p-3\">\n<div class=\"d-flex align-items-start mb-3 no-wrap\">\n<div class=\"col-auto\">\n                  <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" class=\"me-3 lazy\" width=\"50\" alt=\"remote ix\" data-src=\"\/wp-content\/uploads\/rix.svg\">\n               <\/div>\n<div data-mh=\"des-adv1\" class=\"fs-7 mb-4\">La singularidad del acceso remoto de IPTP Networks a los intercambios de Internet y peers privados, a trav&eacute;s de backbones L2 EoMPLS protegidos, es que brinda una m&aacute;xima flexibilidad que te ayudar&aacute; a crear sus propias soluciones de dise&ntilde;o e ingenier&iacute;a de tr&aacute;fico desde un solo puerto.<\/div>\n<\/div>\n<div class=\"d-flex justify-content-between btn-hidden-request align-items-center\">\n               <button class=\"btn btn-secondary border-0 px-3 rounded-lg js-target-div text-white\" data-target=\"remoteix_modal\">Solicitar presupuesto<\/button><br>\n               <a href=\"https:\/\/web.la.iptp.net\/es_ES\/internet-access\/remote-ix\/\" class=\"ms-auto\">Saber m&aacute;s<\/a><br>\n               \t\r\n\r\n\t\r\n\t<div>\r\n\t\t<button type=\"button\" class=\"btn btn-primary btn__jumboix btn-lg js-target-div mt-2 js-fixed-button-open-request-form \" data-target=\"remoteix_modal\">\r\n\t\t\tRequest a quote\t\t<\/button>\r\n\t<\/div>\r\n\t\r\n\t<script type=\"text\/javascript\">\r\n\t\tjQuery(function($){\r\n\r\n\t\t\t $(document).on('click', '#remoteix_modal.active', function(e){\r\n\t\t        e.preventDefault();\r\n\r\n\t\t        $(this).find('.js-x-close').trigger('click');   \r\n\t\t    });\r\n\r\n\t\t    $(document).on('click', '#remoteix_modal.active *', function(e){\r\n\t\t        e.stopPropagation();\r\n\r\n\t\t    });\r\n\r\n\t\t})\r\n\t<\/script>\r\n\r\n\t<div id=\"remoteix_modal\" class=\"popup-jumboIX-modal-s1 wrap-jumboix wrap-jumboix__2 v-modal\">\r\n\t\t<div class=\"modal__inner\">\r\n\t\t\t<button class=\"x-close js-x-close\">x<\/button>\r\n\r\n\t\t\t<h2 class=\"jumbolix-heading \">\r\n\t\t\t\tRequest a quote for Remote IX\t\t\t<\/h2>\r\n\r\n\t\t\t\r\n\t\t\t<form method=\"post\" class=\"js-form-ajax-request_form css-form-mod-v2 js_form_get_token\">\r\n\t\t\t\t   <input type=\"hidden\" name=\"_wp_http_referer\" value=\"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/22055\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"_current_title\" value=\"IPTP Networks\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"security\" value=\"39862701f1\">\r\n   <input type=\"hidden\" name=\"form_time\" value=\"1778670578\">\r\n   <input type=\"text\" name=\"website\" style=\"display:none\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"js_check\" class=\"no-check\" value=\"\">\r\n   \r\n\r\n\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"service\" value=\"Remote IX\">\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"your_name\" class=\"form-control form-control--border-bottom\" placeholder=\"Your name *\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"email\" class=\"form-control form-control--border-bottom\" placeholder=\"E-mail *\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"organisation\" class=\"form-control form-control--border-bottom\" placeholder=\"Organisation *\">\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<div class=\"wrap-intl-tel-input\">\r\n\t\t\t\t\t\t\t<input type=\"text\" name=\"asnumber\" class=\"form-control form-control--border-bottom intl-tel-input no-check\" placeholder=\"Phone Number\">\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 line-group\">\r\n\t\t\t\t\t\t<div class=\"w-100\">\r\n\t\t\t\t\t\t\t<label style=\"font-weight: bold\" for=\"ms\">Describe your request<\/label>\r\n\t\t\t\t\t\t\t<textarea name=\"message\" id=\"ms\" cols=\"30\" rows=\"6\" class=\"form-control form-control--border-bottom\" placeholder=\"Quick overview *\"><\/textarea>\r\n\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 line-group\">\r\n\t\t\t\t\t\t* required fields\t\t\t\t\t<\/div>\r\n\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 text-center\">\r\n\t\t\t\t\t<!-- \t<div class=\"line-group captcha_md\">\r\n\t\t\t\t\t\t\t<div id=\"captchas\" class=\"captcha__label\" data-qid=\"captcha_6a045bf2cc8c7\"><\/div>\r\n\t\t\t\t\t\t\t<span class=\"fa fa-refresh catpcha_refreshs catpcha_refresh_mod\"><\/span>\r\n\t\t\t\t\t\t\t<input id=\"cpatchaJumboIX\" type=\"text\" name=\"captcha\" class=\"line-group__input--213 captcha__input--custom\" placeholder=\"Captcha code\" \/>\r\n\t\t\t\t\t\t<\/div> -->\r\n\t\t\t\t\t\t<div class=\"line-groups\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"hidden-sm hidden-xs\"><\/div>\r\n\t\t\t\t\t\t\t<button class=\"btn btn__jumboix\">\r\n\t\t\t\t\t\t\t\tRequest a quote\t\t\t\t\t\t\t<\/button>\r\n\t\t\t\t\t\t<\/div>\r\n\r\n\r\n\r\n\t\t\t\t\t\t<div class=\"jumboIX_completed js-jumboIX_completed--success \">\r\n\t\t\t\t\t\t\tThank you for your request\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div class=\"jumboIX_completed jumboIX_completed--error\"><\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/form>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<div class=\"div-overlay\"><\/div>\r\n\n            <\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"col-auto col-md-6\">\n<div class=\"box-adv1 bg-primary rounded-lg p-2\">\n<h4 class=\"fw-normal mb-3 text-white\">IX Transit<\/h4>\n<div class=\"bg-white rounded-lg p-3\">\n<div class=\"d-flex align-items-start mb-3 no-wrap\">\n<div class=\"col-auto\">\n                  <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" class=\"me-3 lazy\" width=\"50\" alt=\"remote ix\" data-src=\"\/wp-content\/uploads\/ixt.svg\">\n               <\/div>\n<div data-mh=\"des-adv1\" class=\"fs-7 mb-4\">IX Transit es un producto &uacute;nico de capa 3 dise&ntilde;ado para Proveedores de Servicios de Internet (ISP) y empresas interesadas en optimizar sus redes por s&iacute; mismas. IX Transit es b&aacute;sicamente un IP Transit parcial con una rica comunidad BGP, configurada para administrar anuncios salientes y filtrado flexible de los prefijos recibidos.<\/div>\n<\/div>\n<div class=\"d-flex justify-content-between align-items-center btn-hidden-request\">\n               <button class=\"btn btn-secondary border-0 px-3 rounded-lg js-target-div text-white\" data-target=\"iptransit__modal\">Solicitar presupuesto<\/button><br>\n               <a href=\"https:\/\/web.la.iptp.net\/es_ES\/internet-access\/ix-transit\/\" class=\"ms-auto\">Saber m&aacute;s<\/a><br>\n               \t\r\n\r\n\t\r\n\t<div>\r\n\t\t<button type=\"button\" class=\"btn btn-primary btn__jumboix btn-lg js-target-div mt-2 js-fixed-button-open-request-form \" data-target=\"iptransit__modal\">\r\n\t\t\tRequest a quote\t\t<\/button>\r\n\t<\/div>\r\n\t\r\n\t<script type=\"text\/javascript\">\r\n\t\tjQuery(function($){\r\n\r\n\t\t\t $(document).on('click', '#iptransit__modal.active', function(e){\r\n\t\t        e.preventDefault();\r\n\r\n\t\t        $(this).find('.js-x-close').trigger('click');   \r\n\t\t    });\r\n\r\n\t\t    $(document).on('click', '#iptransit__modal.active *', function(e){\r\n\t\t        e.stopPropagation();\r\n\r\n\t\t    });\r\n\r\n\t\t})\r\n\t<\/script>\r\n\r\n\t<div id=\"iptransit__modal\" class=\"popup-jumboIX-modal-s1 wrap-jumboix wrap-jumboix__2 v-modal\">\r\n\t\t<div class=\"modal__inner\">\r\n\t\t\t<button class=\"x-close js-x-close\">x<\/button>\r\n\r\n\t\t\t<h2 class=\"jumbolix-heading \">\r\n\t\t\t\tRequest a quote for IX Transit\t\t\t<\/h2>\r\n\r\n\t\t\t\r\n\t\t\t<form method=\"post\" class=\"js-form-ajax-request_form css-form-mod-v2 js_form_get_token\">\r\n\t\t\t\t   <input type=\"hidden\" name=\"_wp_http_referer\" value=\"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/22055\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"_current_title\" value=\"IPTP Networks\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"security\" value=\"39862701f1\">\r\n   <input type=\"hidden\" name=\"form_time\" value=\"1778670578\">\r\n   <input type=\"text\" name=\"website\" style=\"display:none\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"js_check\" class=\"no-check\" value=\"\">\r\n   \r\n\r\n\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"service\" value=\"IX Transit\">\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"your_name\" class=\"form-control form-control--border-bottom\" placeholder=\"Your name *\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"email\" class=\"form-control form-control--border-bottom\" placeholder=\"E-mail *\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"organisation\" class=\"form-control form-control--border-bottom\" placeholder=\"Organisation *\">\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<div class=\"wrap-intl-tel-input\">\r\n\t\t\t\t\t\t\t<input type=\"text\" name=\"asnumber\" class=\"form-control form-control--border-bottom intl-tel-input no-check\" placeholder=\"Phone Number\">\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 line-group\">\r\n\t\t\t\t\t\t<div class=\"w-100\">\r\n\t\t\t\t\t\t\t<label style=\"font-weight: bold\" for=\"ms\">Describe your request<\/label>\r\n\t\t\t\t\t\t\t<textarea name=\"message\" id=\"ms\" cols=\"30\" rows=\"6\" class=\"form-control form-control--border-bottom\" placeholder=\"Quick overview *\"><\/textarea>\r\n\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 line-group\">\r\n\t\t\t\t\t\t* required fields\t\t\t\t\t<\/div>\r\n\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 text-center\">\r\n\t\t\t\t\t<!-- \t<div class=\"line-group captcha_md\">\r\n\t\t\t\t\t\t\t<div id=\"captchas\" class=\"captcha__label\" data-qid=\"captcha_6a045bf2cca4a\"><\/div>\r\n\t\t\t\t\t\t\t<span class=\"fa fa-refresh catpcha_refreshs catpcha_refresh_mod\"><\/span>\r\n\t\t\t\t\t\t\t<input id=\"cpatchaJumboIX\" type=\"text\" name=\"captcha\" class=\"line-group__input--213 captcha__input--custom\" placeholder=\"Captcha code\" \/>\r\n\t\t\t\t\t\t<\/div> -->\r\n\t\t\t\t\t\t<div class=\"line-groups\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"hidden-sm hidden-xs\"><\/div>\r\n\t\t\t\t\t\t\t<button class=\"btn btn__jumboix\">\r\n\t\t\t\t\t\t\t\tRequest a quote\t\t\t\t\t\t\t<\/button>\r\n\t\t\t\t\t\t<\/div>\r\n\r\n\r\n\r\n\t\t\t\t\t\t<div class=\"jumboIX_completed js-jumboIX_completed--success \">\r\n\t\t\t\t\t\t\tThank you for your request\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div class=\"jumboIX_completed jumboIX_completed--error\"><\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/form>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<div class=\"div-overlay\"><\/div>\r\n\n            <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":17,"featured_media":0,"parent":276,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-ixp-compare.php","meta":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/22055"}],"collection":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/comments?post=22055"}],"version-history":[{"count":72,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/22055\/revisions"}],"predecessor-version":[{"id":41214,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/22055\/revisions\/41214"}],"up":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/276"}],"wp:attachment":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/media?parent=22055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}