{"id":10766,"date":"2019-07-08T17:26:29","date_gmt":"2019-07-08T14:26:29","guid":{"rendered":"https:\/\/web-dev.iptp.com\/?page_id=10766"},"modified":"2026-04-21T07:00:54","modified_gmt":"2026-04-21T04:00:54","slug":"remote-hands","status":"publish","type":"page","link":"https:\/\/web.la.iptp.net\/es_ES\/network\/datacenter-services\/remote-hands\/","title":{"rendered":"Manos Remotas"},"content":{"rendered":"<p>IPTP Networks trata de hacer que su vida de TI sea lo m&aacute;s f&aacute;cil posible siempre. Por eso ofrecemos nuestro servicio Manos Remotas, para resolver diferentes tipos de tareas t&eacute;cnicas rutinarias y de emergencia. Nuestros ingenieros altamente calificados est&aacute;n disponibles las 24 horas del d&iacute;a, los 7 d&iacute;as de la semana para realizar cualquier tarea de mantenimiento dentro de una instalaci&oacute;n de Colocaci&oacute;n, lo que permite a nuestros clientes mantenerse enfocados en el crecimiento de su negocio sin preocuparse por sus equipos.<\/p><p>Obtendr&aacute;s:<\/p><p><strong>&bull; Trabajo F&iacute;sico:<\/strong> Puede confiar en nosotros en caso de que necesite que su equipo sea movido, colocado en estanter&iacute;as o apilado.<br>\n<strong>&bull; Gesti&oacute;n de Dispositivos Est&aacute;ndar:<\/strong> nuestro personal verificar&aacute; sus dispositivos, sus estados, controlar&aacute; equipos modulares y m&aacute;s.<br>\n<strong>&bull; Log&iacute;stica:<\/strong> El personal de Manos Remotas puede hacerse cargo de todos los procedimientos de env&iacute;o y recepci&oacute;n relacionados con su equipo en nuestras instalaciones.<br>\n<strong>&bull; Cables:<\/strong> Terminaci&oacute;n de conexiones cruzadas, instalaci&oacute;n y mantenimiento, aseguramiento del cableado existente; podemos hacer todo eso.<br>\n<strong>&bull; Auditor&iacute;a de Inventario:<\/strong> Podemos proporcionar auditor&iacute;as de implementaci&oacute;n parcial o total, etiquetado, rastreo de conexiones cruzadas y otros.<br>\n<strong>&bull; Acceso Acompa&ntilde;ado:<\/strong> Puede solicitar a nuestros ingenieros que lo acompa&ntilde;en y le brinden asesor&iacute;a durante su visita a nuestras instalaciones, o usted puede observar y controlar el trabajo de ellos dentro de vuestro espacio.<\/p><p>Las Manos Remotas de IPTP Networks le brindan la mejor atenci&oacute;n posible para ejecutar sus servicios. Nuestros ingenieros altamente calificados est&aacute;n disponibles las 24 horas del d&iacute;a, los 7 d&iacute;as de la semana para realizar cualquier tarea de mantenimiento dentro de una instalaci&oacute;n de colocaci&oacute;n, lo que permite a nuestros clientes mantenerse enfocados en el crecimiento de su negocio sin preocuparse por sus equipos. Manos Remotas es un servicio independiente que puedes solicitar por tu cuenta en las ubicaciones m&aacute;s demandadas como Nueva York, Londres, &Aacute;msterdam, Hong Kong, Tokio y muchas otras m&aacute;s.<\/p><div>\r\n\t\t<button type=\"button\" class=\"btn btn-primary btn__jumboix btn-lg js-target-div mt-2 js-fixed-button-open-request-form \" data-target=\"jumboIX__modal\">\r\n\t\t\tRequest a quote\t\t<\/button>\r\n\t<\/div><script type=\"text\/javascript\">\r\n\t\tjQuery(function($){\r\n\r\n\t\t\t $(document).on('click', '#jumboIX__modal.active', function(e){\r\n\t\t        e.preventDefault();\r\n\r\n\t\t        $(this).find('.js-x-close').trigger('click');   \r\n\t\t    });\r\n\r\n\t\t    $(document).on('click', '#jumboIX__modal.active *', function(e){\r\n\t\t        e.stopPropagation();\r\n\r\n\t\t    });\r\n\r\n\t\t})\r\n\t<\/script><div id=\"jumboIX__modal\" class=\"popup-jumboIX-modal-s1 wrap-jumboix wrap-jumboix__2 v-modal\">\r\n\t\t<div class=\"modal__inner\">\r\n\t\t\t<button class=\"x-close js-x-close\">x<\/button>\r\n\r\n\t\t\t<h2 class=\"jumbolix-heading \">\r\n\t\t\t\tRequest a quote for Remote Hands\t\t\t<\/h2>\r\n\r\n\t\t\t\r\n\t\t\t<form method=\"post\" class=\"js-form-ajax-request_form css-form-mod-v2 js_form_get_token\">\r\n\t\t\t\t   <input type=\"hidden\" name=\"_wp_http_referer\" value=\"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/10766\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"_current_title\" value=\"IPTP Networks\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"security\" value=\"39862701f1\">\r\n   <input type=\"hidden\" name=\"form_time\" value=\"1778671133\">\r\n   <input type=\"text\" name=\"website\" style=\"display:none\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"js_check\" class=\"no-check\" value=\"\">\r\n   \r\n\r\n\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"service\" value=\"Remote Hands\">\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"your_name\" class=\"form-control form-control--border-bottom\" placeholder=\"Your name *\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"email\" class=\"form-control form-control--border-bottom\" placeholder=\"E-mail *\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"organisation\" class=\"form-control form-control--border-bottom\" placeholder=\"Organisation *\">\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<div class=\"wrap-intl-tel-input\">\r\n\t\t\t\t\t\t\t<input type=\"text\" name=\"asnumber\" class=\"form-control form-control--border-bottom intl-tel-input no-check\" placeholder=\"Phone Number\">\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 line-group\">\r\n\t\t\t\t\t\t<div class=\"w-100\">\r\n\t\t\t\t\t\t\t<label style=\"font-weight: bold\" for=\"ms\">Describe your request<\/label>\r\n\t\t\t\t\t\t\t<textarea name=\"message\" id=\"ms\" cols=\"30\" rows=\"6\" class=\"form-control form-control--border-bottom\" placeholder=\"Quick overview *\"><\/textarea>\r\n\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 line-group\">\r\n\t\t\t\t\t\t* required fields\t\t\t\t\t<\/div>\r\n\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 text-center\">\r\n\t\t\t\t\t<!-- \t<div class=\"line-group captcha_md\">\r\n\t\t\t\t\t\t\t<div id=\"captchas\" class=\"captcha__label\" data-qid=\"captcha_6a045e1dcda32\"><\/div>\r\n\t\t\t\t\t\t\t<span class=\"fa fa-refresh catpcha_refreshs catpcha_refresh_mod\"><\/span>\r\n\t\t\t\t\t\t\t<input id=\"cpatchaJumboIX\" type=\"text\" name=\"captcha\" class=\"line-group__input--213 captcha__input--custom\" placeholder=\"Captcha code\" \/>\r\n\t\t\t\t\t\t<\/div> -->\r\n\t\t\t\t\t\t<div class=\"line-groups\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"hidden-sm hidden-xs\"><\/div>\r\n\t\t\t\t\t\t\t<button class=\"btn btn__jumboix\">\r\n\t\t\t\t\t\t\t\tRequest a quote\t\t\t\t\t\t\t<\/button>\r\n\t\t\t\t\t\t<\/div>\r\n\r\n\r\n\r\n\t\t\t\t\t\t<div class=\"jumboIX_completed js-jumboIX_completed--success \">\r\n\t\t\t\t\t\t\tThank you for your request\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div class=\"jumboIX_completed jumboIX_completed--error\"><\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/form>\r\n\t\t<\/div>\r\n\t<\/div><div class=\"div-overlay\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10772,"parent":18393,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/10766"}],"collection":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/comments?post=10766"}],"version-history":[{"count":56,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/10766\/revisions"}],"predecessor-version":[{"id":41722,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/10766\/revisions\/41722"}],"up":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/pages\/18393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/media\/10772"}],"wp:attachment":[{"href":"https:\/\/web.la.iptp.net\/es_ES\/wp-json\/wp\/v2\/media?parent=10766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}